{"id":57387,"date":"2021-09-02T18:56:30","date_gmt":"2021-09-02T16:56:30","guid":{"rendered":"https:\/\/svetslik.si\/nem-kategorizalt\/zirafe\/"},"modified":"2026-03-22T14:30:35","modified_gmt":"2026-03-22T13:30:35","slug":"gyermekfestmenyek-zsirafok","status":"publish","type":"product","link":"https:\/\/svetslik.si\/hu\/gyermekfestmenyek\/gyermekfestmenyek-zsirafok\/","title":{"rendered":"Gyermekfestm\u00e9nyek &#8211; Zsir\u00e1fok"},"content":{"rendered":"<p>Festm\u00e9nyek m\u00e9rete:<br \/>\n50 cm x 50 cm (2 x 25 cm x 50 cm)<br \/>\n60 cm x 60 cm (2 x 30 cm x 60 cm)<br \/>\n80 cm x 80 cm (2 x 40 cm x 80 cm)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Festm\u00e9nyek m\u00e9rete: 50 cm x 50 cm (2 x 25 cm x 50 cm) 60 cm x 60 cm (2 x 30 cm x 60 cm) 80 cm x 80 cm (2 x 40 cm x 80 cm)<\/p>\n","protected":false},"featured_media":49280,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[7125],"product_tag":[7186],"class_list":["post-57387","product","type-product","status-publish","has-post-thumbnail","product_cat-gyermekfestmenyek","product_tag-gyermekfestmenyek","pa_dimenzija-50-x-50-cm","pa_dimenzija-60-x-60-cm","pa_dimenzija-80-x-80-cm","pa_oblika-negyzet","pa_okvir-nincs-keret","pa_podokvir-igen","pa_podokvir-nem","first","onbackorder","purchasable","product-type-variable","has-default-attributes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gyermekfestm\u00e9nyek - Zsir\u00e1fok - 100% k\u00e9zzel festett<\/title>\n<meta name=\"description\" content=\"Gyermekfestm\u00e9nyek - Zsir\u00e1fok - 100% k\u00e9zzel festett v\u00e1szonfestm\u00e9nyek. Festm\u00e9nyek elad\u00e1sa. Egyedi festm\u00e9nyek k\u00e9sz\u00edt\u00e9se megrendel\u00e9sre \u00e9s festm\u00e9nyek keretez\u00e9se.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/svetslik.si\/hu\/gyermekfestmenyek\/gyermekfestmenyek-zsirafok\/\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gyermekfestm\u00e9nyek - Zsir\u00e1fok\" \/>\n<meta property=\"og:description\" content=\"Gyermekfestm\u00e9nyek - Zsir\u00e1fok - 100% k\u00e9zzel festett v\u00e1szonfestm\u00e9nyek. Festm\u00e9nyek elad\u00e1sa. Egyedi festm\u00e9nyek k\u00e9sz\u00edt\u00e9se megrendel\u00e9sre \u00e9s festm\u00e9nyek keretez\u00e9se.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svetslik.si\/hu\/gyermekfestmenyek\/gyermekfestmenyek-zsirafok\/\" \/>\n<meta property=\"og:site_name\" content=\"SvetSlik.si\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/svetslik.si\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-22T13:30:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/08\/image_Zirafe_680.png\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"660\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"100% ro\u010dno naslikane slike na platnu, reprodukcije znanih slikarjev in umetni\u0161ke slike po naro\u010dilu.\" \/>\n<meta name=\"twitter:site\" content=\"@svetslik\" \/>\n<meta name=\"twitter:label1\" content=\"El\u00e9rhet\u0151s\u00e9g\" \/>\n\t<meta name=\"twitter:data1\" content=\"Beszerz\u00e9s alatt\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/gyermekfestmenyek\\\/gyermekfestmenyek-zsirafok\\\/\",\"url\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/gyermekfestmenyek\\\/gyermekfestmenyek-zsirafok\\\/\",\"name\":\"Gyermekfestm\u00e9nyek - Zsir\u00e1fok - 100% k\u00e9zzel festett\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/gyermekfestmenyek\\\/gyermekfestmenyek-zsirafok\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/gyermekfestmenyek\\\/gyermekfestmenyek-zsirafok\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/image_Zirafe_680.png\",\"datePublished\":\"2021-09-02T16:56:30+00:00\",\"dateModified\":\"2026-03-22T13:30:35+00:00\",\"description\":\"Gyermekfestm\u00e9nyek - Zsir\u00e1fok - 100% k\u00e9zzel festett v\u00e1szonfestm\u00e9nyek. Festm\u00e9nyek elad\u00e1sa. Egyedi festm\u00e9nyek k\u00e9sz\u00edt\u00e9se megrendel\u00e9sre \u00e9s festm\u00e9nyek keretez\u00e9se.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/gyermekfestmenyek\\\/gyermekfestmenyek-zsirafok\\\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/svetslik.si\\\/hu\\\/gyermekfestmenyek\\\/gyermekfestmenyek-zsirafok\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/gyermekfestmenyek\\\/gyermekfestmenyek-zsirafok\\\/#primaryimage\",\"url\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/image_Zirafe_680.png\",\"contentUrl\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/image_Zirafe_680.png\",\"width\":680,\"height\":660,\"caption\":\"Gyermek falfestm\u00e9nyek v\u00e1szonra, falfestm\u00e9nyek, m\u0171v\u00e9szeti festm\u00e9nyek, modern festm\u00e9nyek, ambient festm\u00e9nyek, absztrakt festm\u00e9nyek, dekorat\u00edv falfestm\u00e9nyek, festm\u00e9nyek ad\u00e1sv\u00e9tele - Zsir\u00e1fok\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/gyermekfestmenyek\\\/gyermekfestmenyek-zsirafok\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Fali m\u0171v\u00e9szet \u00e9s festm\u00e9nyek v\u00e1szonra\",\"item\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/vaszonfestmenyek-svetslik-si-100-kezzel-festett-festoi-reprodukciok-es-vaszonfestmenyek\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festm\u00e9nyek elad\u00e1sa\",\"item\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/festmenyek-eladasa\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gyermekfestm\u00e9nyek - Zsir\u00e1fok\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/#website\",\"url\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/\",\"name\":\"SvetSlik.si\",\"description\":\"K\u00e9zzel festett festm\u00e9nyek v\u00e1sznon \u2013 h\u00edres fest\u0151k reprodukci\u00f3i, absztrakt \u00e9s modern mot\u00edvumok, egyedi rendel\u00e9sre is.\",\"publisher\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\",\"alternateName\":\"K\u00e9zzel festett festm\u00e9nyek online gal\u00e9ri\u00e1ja\"},{\"@type\":[\"Organization\",\"Store\"],\"@id\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/#organization\",\"name\":\"SvetSlik.si\",\"url\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-512.png\",\"contentUrl\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-512.png\",\"width\":512,\"height\":512,\"caption\":\"SvetSlik.si\"},\"image\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/svetslik.si\",\"https:\\\/\\\/x.com\\\/svetslik\",\"https:\\\/\\\/www.instagram.com\\\/svetslik.si\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/svetslik-si\",\"https:\\\/\\\/www.google.com\\\/maps\\\/place\\\/?q=place_id:ChIJaybyg-XHekcRwZCqYrxOGjY\"],\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Zgornje Bitnje 146a\",\"addressLocality\":\"\u017dabnica\",\"postalCode\":\"4209\",\"addressCountry\":\"SI\"},\"hasMap\":\"https:\\\/\\\/www.google.com\\\/maps\\\/place\\\/?q=place_id:ChIJaybyg-XHekcRwZCqYrxOGjY\",\"telephone\":\"+38651675637\",\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"https:\\\/\\\/schema.org\\\/Monday\",\"https:\\\/\\\/schema.org\\\/Tuesday\",\"https:\\\/\\\/schema.org\\\/Wednesday\",\"https:\\\/\\\/schema.org\\\/Thursday\",\"https:\\\/\\\/schema.org\\\/Friday\"],\"opens\":\"09:00\",\"closes\":\"20:00\"}],\"description\":\"K\u00e9zzel festett v\u00e1szonfestm\u00e9nyek \u2013 rendelje meg online vagy e-mailben. Megtekint\u00e9s el\u0151zetes egyeztet\u00e9s alapj\u00e1n lehets\u00e9ges.\",\"knowsAbout\":[\"v\u00e1szonfestm\u00e9ny\",\"k\u00e9zzel festett v\u00e1szonfestm\u00e9nyek\",\"festm\u00e9nyek reprodukci\u00f3i\",\"olajfestm\u00e9ny v\u00e1szonon\",\"akrilfestm\u00e9ny v\u00e1szonon\",\"modern absztrakt m\u0171v\u00e9szet\",\"festm\u00e9ny megrendel\u00e9sre\",\"festm\u00e9nyek megrendel\u00e9sre\",\"festm\u00e9nyek bekeretez\u00e9se\",\"h\u00edres fest\u0151k alkot\u00e1sai\",\"modern festm\u00e9nyek otthonra\",\"festm\u00e9ny aj\u00e1nd\u00e9kba\",\"egyedi v\u00e1szonfestm\u00e9nyek\",\"festm\u00e9nyek h\u00e1zhozsz\u00e1ll\u00edt\u00e1sa\",\"m\u0171v\u00e9szeti gal\u00e9ria\"],\"legalName\":\"Matemero d.o.o.\",\"email\":\"info@svetslik.si\",\"foundingDate\":\"2009\",\"aggregateRating\":{\"@type\":\"AggregateRating\",\"ratingValue\":\"5\",\"reviewCount\":103,\"bestRating\":\"5\",\"worstRating\":\"1\"}}]}<\/script>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"843__\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gyermekfestm\u00e9nyek - Zsir\u00e1fok - 100% k\u00e9zzel festett","description":"Gyermekfestm\u00e9nyek - Zsir\u00e1fok - 100% k\u00e9zzel festett v\u00e1szonfestm\u00e9nyek. Festm\u00e9nyek elad\u00e1sa. Egyedi festm\u00e9nyek k\u00e9sz\u00edt\u00e9se megrendel\u00e9sre \u00e9s festm\u00e9nyek keretez\u00e9se.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/svetslik.si\/hu\/gyermekfestmenyek\/gyermekfestmenyek-zsirafok\/","og_locale":"hu_HU","og_type":"article","og_title":"Gyermekfestm\u00e9nyek - Zsir\u00e1fok","og_description":"Gyermekfestm\u00e9nyek - Zsir\u00e1fok - 100% k\u00e9zzel festett v\u00e1szonfestm\u00e9nyek. Festm\u00e9nyek elad\u00e1sa. Egyedi festm\u00e9nyek k\u00e9sz\u00edt\u00e9se megrendel\u00e9sre \u00e9s festm\u00e9nyek keretez\u00e9se.","og_url":"https:\/\/svetslik.si\/hu\/gyermekfestmenyek\/gyermekfestmenyek-zsirafok\/","og_site_name":"SvetSlik.si","article_publisher":"https:\/\/www.facebook.com\/svetslik.si","article_modified_time":"2026-03-22T13:30:35+00:00","og_image":[{"width":680,"height":660,"url":"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/08\/image_Zirafe_680.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_description":"100% ro\u010dno naslikane slike na platnu, reprodukcije znanih slikarjev in umetni\u0161ke slike po naro\u010dilu.","twitter_site":"@svetslik","twitter_misc":{"El\u00e9rhet\u0151s\u00e9g":"Beszerz\u00e9s alatt"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/svetslik.si\/hu\/gyermekfestmenyek\/gyermekfestmenyek-zsirafok\/","url":"https:\/\/svetslik.si\/hu\/gyermekfestmenyek\/gyermekfestmenyek-zsirafok\/","name":"Gyermekfestm\u00e9nyek - Zsir\u00e1fok - 100% k\u00e9zzel festett","isPartOf":{"@id":"https:\/\/svetslik.si\/hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/svetslik.si\/hu\/gyermekfestmenyek\/gyermekfestmenyek-zsirafok\/#primaryimage"},"image":{"@id":"https:\/\/svetslik.si\/hu\/gyermekfestmenyek\/gyermekfestmenyek-zsirafok\/#primaryimage"},"thumbnailUrl":"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/08\/image_Zirafe_680.png","datePublished":"2021-09-02T16:56:30+00:00","dateModified":"2026-03-22T13:30:35+00:00","description":"Gyermekfestm\u00e9nyek - Zsir\u00e1fok - 100% k\u00e9zzel festett v\u00e1szonfestm\u00e9nyek. Festm\u00e9nyek elad\u00e1sa. Egyedi festm\u00e9nyek k\u00e9sz\u00edt\u00e9se megrendel\u00e9sre \u00e9s festm\u00e9nyek keretez\u00e9se.","breadcrumb":{"@id":"https:\/\/svetslik.si\/hu\/gyermekfestmenyek\/gyermekfestmenyek-zsirafok\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/svetslik.si\/hu\/gyermekfestmenyek\/gyermekfestmenyek-zsirafok\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/svetslik.si\/hu\/gyermekfestmenyek\/gyermekfestmenyek-zsirafok\/#primaryimage","url":"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/08\/image_Zirafe_680.png","contentUrl":"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/08\/image_Zirafe_680.png","width":680,"height":660,"caption":"Gyermek falfestm\u00e9nyek v\u00e1szonra, falfestm\u00e9nyek, m\u0171v\u00e9szeti festm\u00e9nyek, modern festm\u00e9nyek, ambient festm\u00e9nyek, absztrakt festm\u00e9nyek, dekorat\u00edv falfestm\u00e9nyek, festm\u00e9nyek ad\u00e1sv\u00e9tele - Zsir\u00e1fok"},{"@type":"BreadcrumbList","@id":"https:\/\/svetslik.si\/hu\/gyermekfestmenyek\/gyermekfestmenyek-zsirafok\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Fali m\u0171v\u00e9szet \u00e9s festm\u00e9nyek v\u00e1szonra","item":"https:\/\/svetslik.si\/hu\/vaszonfestmenyek-svetslik-si-100-kezzel-festett-festoi-reprodukciok-es-vaszonfestmenyek\/"},{"@type":"ListItem","position":2,"name":"Festm\u00e9nyek elad\u00e1sa","item":"https:\/\/svetslik.si\/hu\/festmenyek-eladasa\/"},{"@type":"ListItem","position":3,"name":"Gyermekfestm\u00e9nyek - Zsir\u00e1fok"}]},{"@type":"WebSite","@id":"https:\/\/svetslik.si\/hu\/#website","url":"https:\/\/svetslik.si\/hu\/","name":"SvetSlik.si","description":"K\u00e9zzel festett festm\u00e9nyek v\u00e1sznon \u2013 h\u00edres fest\u0151k reprodukci\u00f3i, absztrakt \u00e9s modern mot\u00edvumok, egyedi rendel\u00e9sre is.","publisher":{"@id":"https:\/\/svetslik.si\/hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svetslik.si\/hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu","alternateName":"K\u00e9zzel festett festm\u00e9nyek online gal\u00e9ri\u00e1ja"},{"@type":["Organization","Store"],"@id":"https:\/\/svetslik.si\/hu\/#organization","name":"SvetSlik.si","url":"https:\/\/svetslik.si\/hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/svetslik.si\/hu\/#\/schema\/logo\/image\/","url":"https:\/\/svetslik.si\/wp-content\/uploads\/2020\/12\/logo-512.png","contentUrl":"https:\/\/svetslik.si\/wp-content\/uploads\/2020\/12\/logo-512.png","width":512,"height":512,"caption":"SvetSlik.si"},"image":{"@id":"https:\/\/svetslik.si\/hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/svetslik.si","https:\/\/x.com\/svetslik","https:\/\/www.instagram.com\/svetslik.si\/","https:\/\/www.linkedin.com\/company\/svetslik-si","https:\/\/www.google.com\/maps\/place\/?q=place_id:ChIJaybyg-XHekcRwZCqYrxOGjY"],"address":{"@type":"PostalAddress","streetAddress":"Zgornje Bitnje 146a","addressLocality":"\u017dabnica","postalCode":"4209","addressCountry":"SI"},"hasMap":"https:\/\/www.google.com\/maps\/place\/?q=place_id:ChIJaybyg-XHekcRwZCqYrxOGjY","telephone":"+38651675637","openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["https:\/\/schema.org\/Monday","https:\/\/schema.org\/Tuesday","https:\/\/schema.org\/Wednesday","https:\/\/schema.org\/Thursday","https:\/\/schema.org\/Friday"],"opens":"09:00","closes":"20:00"}],"description":"K\u00e9zzel festett v\u00e1szonfestm\u00e9nyek \u2013 rendelje meg online vagy e-mailben. Megtekint\u00e9s el\u0151zetes egyeztet\u00e9s alapj\u00e1n lehets\u00e9ges.","knowsAbout":["v\u00e1szonfestm\u00e9ny","k\u00e9zzel festett v\u00e1szonfestm\u00e9nyek","festm\u00e9nyek reprodukci\u00f3i","olajfestm\u00e9ny v\u00e1szonon","akrilfestm\u00e9ny v\u00e1szonon","modern absztrakt m\u0171v\u00e9szet","festm\u00e9ny megrendel\u00e9sre","festm\u00e9nyek megrendel\u00e9sre","festm\u00e9nyek bekeretez\u00e9se","h\u00edres fest\u0151k alkot\u00e1sai","modern festm\u00e9nyek otthonra","festm\u00e9ny aj\u00e1nd\u00e9kba","egyedi v\u00e1szonfestm\u00e9nyek","festm\u00e9nyek h\u00e1zhozsz\u00e1ll\u00edt\u00e1sa","m\u0171v\u00e9szeti gal\u00e9ria"],"legalName":"Matemero d.o.o.","email":"info@svetslik.si","foundingDate":"2009","aggregateRating":{"@type":"AggregateRating","ratingValue":"5","reviewCount":103,"bestRating":"5","worstRating":"1"}}]},"og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"843__","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/svetslik.si\/hu\/wp-json\/wp\/v2\/product\/57387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/svetslik.si\/hu\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/svetslik.si\/hu\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/svetslik.si\/hu\/wp-json\/wp\/v2\/media\/49280"}],"wp:attachment":[{"href":"https:\/\/svetslik.si\/hu\/wp-json\/wp\/v2\/media?parent=57387"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/svetslik.si\/hu\/wp-json\/wp\/v2\/product_brand?post=57387"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/svetslik.si\/hu\/wp-json\/wp\/v2\/product_cat?post=57387"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/svetslik.si\/hu\/wp-json\/wp\/v2\/product_tag?post=57387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}