{"id":61823,"date":"2023-03-07T08:04:27","date_gmt":"2023-03-07T07:04:27","guid":{"rendered":"https:\/\/svetslik.si\/nem-kategorizalt\/abstraktna-slika-w38\/"},"modified":"2024-07-11T14:23:32","modified_gmt":"2024-07-11T12:23:32","slug":"abstrakt-festmeny-w38","status":"publish","type":"product","link":"https:\/\/svetslik.si\/hu\/tobbreszes-vaszonfalikepek\/abstrakt-festmeny-w38\/","title":{"rendered":"Modern festm\u00e9ny \u2013 Selyem \u00e9s arany"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row css=\u201d.vc_custom_1678118371009{margin-bottom: 10px !important;}\u201d][vc_column]\t<div class=\"et-image-32 et-image     et_image_link\">\n\t\t<div class=\"et-image-inner \">\n\t\t\t\t\t\t\t<div class=\"et-image-thumb \">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"1027\" src=\"https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38.jpg\" class=\"attachment-full\" alt=\"Abstrakt festm\u00e9ny - W38\" title=\"Abstrakt festm\u00e9ny - W38\" srcset=\"https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38.jpg 1440w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38-600x428.jpg 600w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38-1200x856.jpg 1200w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38-300x214.jpg 300w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38-1024x730.jpg 1024w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38-768x548.jpg 768w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38-18x12.jpg 18w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38-150x107.jpg 150w\" sizes=\"auto, (max-width: 1440px) 100vw, 1440px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n  [\/vc_column][\/vcrow_rows][\/vcrow_rows =\u201d.vc_custom_1678118371009{margin-bottom: 10px !important;}\u201d][vc_column]\t<div class=\"et-image-436 et-image     et_image_link\">\n\t\t<div class=\"et-image-inner \">\n\t\t\t\t\t\t\t<div class=\"et-image-thumb \">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1240\" height=\"884\" src=\"https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38a.jpg\" class=\"attachment-full\" alt=\"Abstrakt festm\u00e9ny - W38\" title=\"Abstrakt festm\u00e9ny - W38\" srcset=\"https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38a.jpg 1240w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38a-600x428.jpg 600w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38a-1200x855.jpg 1200w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38a-300x214.jpg 300w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38a-1024x730.jpg 1024w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38a-768x548.jpg 768w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38a-18x12.jpg 18w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38a-150x107.jpg 150w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n  [\/vc_column][=\u201d\/vc_row][vc_row. vc_custom_1678118371009{margin-bottom: 10px !important;}\u201d][vc_column]\t<div class=\"et-image-684 et-image     et_image_link\">\n\t\t<div class=\"et-image-inner \">\n\t\t\t\t\t\t\t<div class=\"et-image-thumb \">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1240\" height=\"884\" src=\"https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38b.jpg\" class=\"attachment-full\" alt=\"Abstrakt festm\u00e9ny - W38\" title=\"Abstrakt festm\u00e9ny - W38\" srcset=\"https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38b.jpg 1240w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38b-600x428.jpg 600w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38b-1200x855.jpg 1200w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38b-300x214.jpg 300w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38b-1024x730.jpg 1024w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38b-768x548.jpg 768w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38b-18x12.jpg 18w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38b-150x107.jpg 150w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n  [\/vc_column][\/vc_row][vc_row][v_c]\nFestm\u00e9nyek m\u00e9rete:<br \/>\n50 cm x 50 cm (150 cm x 50 cm)<br \/>\n60 cm x 60 cm (180 cm x 60 cm)<br \/>\n80 cm x 80 cm (240 cm x 80 cm)<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=\u201d.vc_custom_1678118371009{margin-bottom: 10px !important;}\u201d][vc_column][\/vc_column][\/vcrow_rows][\/vcrow_rows =\u201d.vc_custom_1678118371009{margin-bottom: 10px !important;}\u201d][vc_column][\/vc_column][=\u201d\/vc_row][vc_row. vc_custom_1678118371009{margin-bottom: 10px !important;}\u201d][vc_column][\/vc_column][\/vc_row][vc_row][v_c] Festm\u00e9nyek m\u00e9rete: 50 cm x 50 cm (150 cm x 50 cm) 60 cm x 60 cm (180 cm x 60 cm) 80 cm x 80 cm (240 cm x 80 cm)<\/p>\n","protected":false},"featured_media":51686,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[7154],"product_tag":[11945,11952,11955,11951,11949,11947,7217],"class_list":["post-61823","product","type-product","status-publish","has-post-thumbnail","product_cat-tobbreszes-vaszonfalikepek","product_tag-abstraktne-slike-hu","product_tag-moderne-slike-hu","product_tag-slike-na-platnu-hu","product_tag-slike-za-dnevno-sobo-hu","product_tag-slike-za-v-dnevno-sobo-hu","product_tag-stenske-slike-hu","product_tag-tobbreszes-festmenyek","pa_dimenzija-100-x-300-cm","pa_dimenzija-150-x-50-cm","pa_dimenzija-180-x-60-cm","pa_dimenzija-240-x-80-cm","pa_dimenzija-40-x-120-cm","pa_dimenzija-70-x-210-cm","pa_dimenzija-90-x-270-cm","pa_oblika-vizszintes","pa_pod-okvir-arban-benne","first","onbackorder","purchasable","product-type-variable","has-default-attributes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Modern festm\u00e9ny \u2013 Selyem \u00e9s arany - SVETSLIK.SI - 100% k\u00e9zzel festett<\/title>\n<meta name=\"description\" content=\"Modern festm\u00e9ny \u2013 Selyem \u00e9s arany - 100% k\u00e9zzel festett v\u00e1szonfestm\u00e9nyek. Festm\u00e9nyek elad\u00e1sa - moderne festm\u00e9nyek, absztrakt festm\u00e9nyek, olajfestm\u00e9nyek, egyedi rendel\u00e9sre k\u00e9sz\u00edtett festm\u00e9nyek \u00e9s k\u00e9pkeretez\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/svetslik.si\/hu\/tobbreszes-vaszonfalikepek\/abstrakt-festmeny-w38\/\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modern festm\u00e9ny \u2013 Selyem \u00e9s arany\" \/>\n<meta property=\"og:description\" content=\"H\u00edres fest\u0151k 100%-ban k\u00e9zzel festett reprodukci\u00f3i, absztrakt k\u00e9pek, v\u00e1szon falik\u00e9pek, modern festm\u00e9nyek \u00e9s egyedi rendel\u00e9sre k\u00e9sz\u00edtett k\u00e9pek.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svetslik.si\/hu\/tobbreszes-vaszonfalikepek\/abstrakt-festmeny-w38\/\" \/>\n<meta property=\"og:site_name\" content=\"SVETSLIK.SI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/svetslik.si\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-11T12:23:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1022\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@svetslik\" \/>\n<meta name=\"twitter:label1\" content=\"El\u00e9rhet\u0151s\u00e9g\" \/>\n\t<meta name=\"twitter:data1\" content=\"Beszerz\u00e9s alatt\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/tobbreszes-vaszonfalikepek\\\/abstrakt-festmeny-w38\\\/\",\"url\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/tobbreszes-vaszonfalikepek\\\/abstrakt-festmeny-w38\\\/\",\"name\":\"Modern festm\u00e9ny \u2013 Selyem \u00e9s arany - SVETSLIK.SI - 100% k\u00e9zzel festett\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/tobbreszes-vaszonfalikepek\\\/abstrakt-festmeny-w38\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/tobbreszes-vaszonfalikepek\\\/abstrakt-festmeny-w38\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/abstraktna-slika-W38.png\",\"datePublished\":\"2023-03-07T07:04:27+00:00\",\"dateModified\":\"2024-07-11T12:23:32+00:00\",\"description\":\"Modern festm\u00e9ny \u2013 Selyem \u00e9s arany - 100% k\u00e9zzel festett v\u00e1szonfestm\u00e9nyek. Festm\u00e9nyek elad\u00e1sa - moderne festm\u00e9nyek, absztrakt festm\u00e9nyek, olajfestm\u00e9nyek, egyedi rendel\u00e9sre k\u00e9sz\u00edtett festm\u00e9nyek \u00e9s k\u00e9pkeretez\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/tobbreszes-vaszonfalikepek\\\/abstrakt-festmeny-w38\\\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/svetslik.si\\\/hu\\\/tobbreszes-vaszonfalikepek\\\/abstrakt-festmeny-w38\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/tobbreszes-vaszonfalikepek\\\/abstrakt-festmeny-w38\\\/#primaryimage\",\"url\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/abstraktna-slika-W38.png\",\"contentUrl\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/abstraktna-slika-W38.png\",\"width\":1022,\"height\":330,\"caption\":\"Abstrakt festm\u00e9ny - W38\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/tobbreszes-vaszonfalikepek\\\/abstrakt-festmeny-w38\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Fali m\u0171v\u00e9szet \u00e9s festm\u00e9nyek v\u00e1szonra\",\"item\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festm\u00e9nyek elad\u00e1sa\",\"item\":\"https:\\\/\\\/svetslik.si\\\/prodaja-slik\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Abstrakt festm\u00e9ny &#8211; W38\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/#website\",\"url\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/\",\"name\":\"SVETSLIK.SI\",\"description\":\"H\u00edres fest\u0151k 100%-ban k\u00e9zzel festett reprodukci\u00f3i, absztrakt k\u00e9pek, v\u00e1szon falik\u00e9pek, modern festm\u00e9nyek \u00e9s egyedi rendel\u00e9sre k\u00e9sz\u00edtett k\u00e9pek.\",\"publisher\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":[\"Organization\",\"Store\"],\"@id\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/#organization\",\"name\":\"SvetSlik.si\",\"url\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-512.png\",\"contentUrl\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-512.png\",\"width\":512,\"height\":512,\"caption\":\"SvetSlik.si\"},\"image\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/svetslik.si\",\"https:\\\/\\\/x.com\\\/svetslik\",\"https:\\\/\\\/www.instagram.com\\\/svetslik.si\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/svetslik-si\"],\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Zgornje Bitnje 146a\",\"addressLocality\":\"\u017dabnica\",\"postalCode\":\"4209\",\"addressCountry\":\"SI\"},\"hasMap\":\"https:\\\/\\\/www.google.com\\\/maps\\\/place\\\/?q=place_id:ChIJaybyg-XHekcRwZCqYrxOGjY\",\"telephone\":\"+38651675637\",\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"https:\\\/\\\/schema.org\\\/Monday\",\"https:\\\/\\\/schema.org\\\/Tuesday\",\"https:\\\/\\\/schema.org\\\/Wednesday\",\"https:\\\/\\\/schema.org\\\/Thursday\",\"https:\\\/\\\/schema.org\\\/Friday\"],\"opens\":\"09:00\",\"closes\":\"20:00\"}],\"description\":\"K\u00e9zzel festett v\u00e1szonk\u00e9pek \u2013 rendelje meg online vagy e-mailben. Megtekint\u00e9s el\u0151zetes egyeztet\u00e9s alapj\u00e1n lehets\u00e9ges.\",\"knowsAbout\":[\"v\u00e1szonk\u00e9p\",\"k\u00e9zzel festett v\u00e1szonk\u00e9pek\",\"festm\u00e9nyek reprodukci\u00f3i\",\"olajfestm\u00e9ny v\u00e1szonon\",\"akrilfestm\u00e9ny v\u00e1szonon\",\"modern absztrakt m\u0171v\u00e9szet\",\"festm\u00e9ny megrendel\u00e9sre\",\"k\u00e9pek megrendel\u00e9sre\",\"k\u00e9pek bekeretez\u00e9se\",\"h\u00edres fest\u0151k alkot\u00e1sai\",\"modern k\u00e9pek otthonra\",\"festm\u00e9ny aj\u00e1nd\u00e9kba\",\"egyedi v\u00e1szonk\u00e9pek\",\"k\u00e9pek h\u00e1zhozsz\u00e1ll\u00edt\u00e1sa\",\"m\u0171v\u00e9szeti gal\u00e9ria\"]}]}<\/script>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"745__-2-1\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Modern festm\u00e9ny \u2013 Selyem \u00e9s arany - SVETSLIK.SI - 100% k\u00e9zzel festett","description":"Modern festm\u00e9ny \u2013 Selyem \u00e9s arany - 100% k\u00e9zzel festett v\u00e1szonfestm\u00e9nyek. Festm\u00e9nyek elad\u00e1sa - moderne festm\u00e9nyek, absztrakt festm\u00e9nyek, olajfestm\u00e9nyek, egyedi rendel\u00e9sre k\u00e9sz\u00edtett festm\u00e9nyek \u00e9s k\u00e9pkeretez\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/svetslik.si\/hu\/tobbreszes-vaszonfalikepek\/abstrakt-festmeny-w38\/","og_locale":"hu_HU","og_type":"article","og_title":"Modern festm\u00e9ny \u2013 Selyem \u00e9s arany","og_description":"H\u00edres fest\u0151k 100%-ban k\u00e9zzel festett reprodukci\u00f3i, absztrakt k\u00e9pek, v\u00e1szon falik\u00e9pek, modern festm\u00e9nyek \u00e9s egyedi rendel\u00e9sre k\u00e9sz\u00edtett k\u00e9pek.","og_url":"https:\/\/svetslik.si\/hu\/tobbreszes-vaszonfalikepek\/abstrakt-festmeny-w38\/","og_site_name":"SVETSLIK.SI","article_publisher":"https:\/\/www.facebook.com\/svetslik.si","article_modified_time":"2024-07-11T12:23:32+00:00","og_image":[{"width":1022,"height":330,"url":"https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@svetslik","twitter_misc":{"El\u00e9rhet\u0151s\u00e9g":"Beszerz\u00e9s alatt"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/svetslik.si\/hu\/tobbreszes-vaszonfalikepek\/abstrakt-festmeny-w38\/","url":"https:\/\/svetslik.si\/hu\/tobbreszes-vaszonfalikepek\/abstrakt-festmeny-w38\/","name":"Modern festm\u00e9ny \u2013 Selyem \u00e9s arany - SVETSLIK.SI - 100% k\u00e9zzel festett","isPartOf":{"@id":"https:\/\/svetslik.si\/hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/svetslik.si\/hu\/tobbreszes-vaszonfalikepek\/abstrakt-festmeny-w38\/#primaryimage"},"image":{"@id":"https:\/\/svetslik.si\/hu\/tobbreszes-vaszonfalikepek\/abstrakt-festmeny-w38\/#primaryimage"},"thumbnailUrl":"https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38.png","datePublished":"2023-03-07T07:04:27+00:00","dateModified":"2024-07-11T12:23:32+00:00","description":"Modern festm\u00e9ny \u2013 Selyem \u00e9s arany - 100% k\u00e9zzel festett v\u00e1szonfestm\u00e9nyek. Festm\u00e9nyek elad\u00e1sa - moderne festm\u00e9nyek, absztrakt festm\u00e9nyek, olajfestm\u00e9nyek, egyedi rendel\u00e9sre k\u00e9sz\u00edtett festm\u00e9nyek \u00e9s k\u00e9pkeretez\u00e9s.","breadcrumb":{"@id":"https:\/\/svetslik.si\/hu\/tobbreszes-vaszonfalikepek\/abstrakt-festmeny-w38\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/svetslik.si\/hu\/tobbreszes-vaszonfalikepek\/abstrakt-festmeny-w38\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/svetslik.si\/hu\/tobbreszes-vaszonfalikepek\/abstrakt-festmeny-w38\/#primaryimage","url":"https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38.png","contentUrl":"https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktna-slika-W38.png","width":1022,"height":330,"caption":"Abstrakt festm\u00e9ny - W38"},{"@type":"BreadcrumbList","@id":"https:\/\/svetslik.si\/hu\/tobbreszes-vaszonfalikepek\/abstrakt-festmeny-w38\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Fali m\u0171v\u00e9szet \u00e9s festm\u00e9nyek v\u00e1szonra","item":"https:\/\/svetslik.si\/hu\/"},{"@type":"ListItem","position":2,"name":"Festm\u00e9nyek elad\u00e1sa","item":"https:\/\/svetslik.si\/prodaja-slik\/"},{"@type":"ListItem","position":3,"name":"Abstrakt festm\u00e9ny &#8211; W38"}]},{"@type":"WebSite","@id":"https:\/\/svetslik.si\/hu\/#website","url":"https:\/\/svetslik.si\/hu\/","name":"SVETSLIK.SI","description":"H\u00edres fest\u0151k 100%-ban k\u00e9zzel festett reprodukci\u00f3i, absztrakt k\u00e9pek, v\u00e1szon falik\u00e9pek, modern festm\u00e9nyek \u00e9s egyedi rendel\u00e9sre k\u00e9sz\u00edtett k\u00e9pek.","publisher":{"@id":"https:\/\/svetslik.si\/hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svetslik.si\/hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":["Organization","Store"],"@id":"https:\/\/svetslik.si\/hu\/#organization","name":"SvetSlik.si","url":"https:\/\/svetslik.si\/hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/svetslik.si\/hu\/#\/schema\/logo\/image\/","url":"https:\/\/svetslik.si\/wp-content\/uploads\/2020\/12\/logo-512.png","contentUrl":"https:\/\/svetslik.si\/wp-content\/uploads\/2020\/12\/logo-512.png","width":512,"height":512,"caption":"SvetSlik.si"},"image":{"@id":"https:\/\/svetslik.si\/hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/svetslik.si","https:\/\/x.com\/svetslik","https:\/\/www.instagram.com\/svetslik.si\/","https:\/\/www.linkedin.com\/company\/svetslik-si"],"address":{"@type":"PostalAddress","streetAddress":"Zgornje Bitnje 146a","addressLocality":"\u017dabnica","postalCode":"4209","addressCountry":"SI"},"hasMap":"https:\/\/www.google.com\/maps\/place\/?q=place_id:ChIJaybyg-XHekcRwZCqYrxOGjY","telephone":"+38651675637","openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["https:\/\/schema.org\/Monday","https:\/\/schema.org\/Tuesday","https:\/\/schema.org\/Wednesday","https:\/\/schema.org\/Thursday","https:\/\/schema.org\/Friday"],"opens":"09:00","closes":"20:00"}],"description":"K\u00e9zzel festett v\u00e1szonk\u00e9pek \u2013 rendelje meg online vagy e-mailben. Megtekint\u00e9s el\u0151zetes egyeztet\u00e9s alapj\u00e1n lehets\u00e9ges.","knowsAbout":["v\u00e1szonk\u00e9p","k\u00e9zzel festett v\u00e1szonk\u00e9pek","festm\u00e9nyek reprodukci\u00f3i","olajfestm\u00e9ny v\u00e1szonon","akrilfestm\u00e9ny v\u00e1szonon","modern absztrakt m\u0171v\u00e9szet","festm\u00e9ny megrendel\u00e9sre","k\u00e9pek megrendel\u00e9sre","k\u00e9pek bekeretez\u00e9se","h\u00edres fest\u0151k alkot\u00e1sai","modern k\u00e9pek otthonra","festm\u00e9ny aj\u00e1nd\u00e9kba","egyedi v\u00e1szonk\u00e9pek","k\u00e9pek h\u00e1zhozsz\u00e1ll\u00edt\u00e1sa","m\u0171v\u00e9szeti gal\u00e9ria"]}]},"og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"745__-2-1","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/svetslik.si\/hu\/wp-json\/wp\/v2\/product\/61823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/svetslik.si\/hu\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/svetslik.si\/hu\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/svetslik.si\/hu\/wp-json\/wp\/v2\/media\/51686"}],"wp:attachment":[{"href":"https:\/\/svetslik.si\/hu\/wp-json\/wp\/v2\/media?parent=61823"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/svetslik.si\/hu\/wp-json\/wp\/v2\/product_brand?post=61823"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/svetslik.si\/hu\/wp-json\/wp\/v2\/product_cat?post=61823"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/svetslik.si\/hu\/wp-json\/wp\/v2\/product_tag?post=61823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}