{"id":38056,"date":"2021-09-02T17:42:32","date_gmt":"2021-09-02T15:42:32","guid":{"rendered":"https:\/\/svetslik.si\/senza-categoria\/the-water-lily-pond-aka-japanese-bridge\/"},"modified":"2026-03-22T21:01:16","modified_gmt":"2026-03-22T20:01:16","slug":"the-water-lily-pond-aka-japanese-bridge","status":"publish","type":"product","link":"https:\/\/svetslik.si\/it\/claude-monet\/the-water-lily-pond-aka-japanese-bridge\/","title":{"rendered":"Claude Monet \u2013 Lo stagno delle ninfee (Ponte giapponese)"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text]\n<h1>Claude Monet \u2013 Lo stagno delle ninfee (noto anche come ponte giapponese)<\/h1>\n<p>\u00a0<\/p>\n<table border=\"0\" width=\"632\" cellspacing=\"0\" cellpadding=\"0\">\n<tr>\n<td height=\"21\">Anno di creazione:<\/td>\n<td style=\"width: 452px\">1899<\/td>\n<\/tr>\n<tr>\n<td height=\"21\">Dimensione originale:<\/td>\n<td style=\"width: 452px\">73,3 cm x 92,7 cm<\/td>\n<\/tr>\n<tr>\n<td height=\"21\">Stile colore:<\/td>\n<td style=\"width: 452px\">Impressionismo<\/td>\n<\/tr>\n<tr>\n<td height=\"21\">Tecnica originale:<\/td>\n<td>Olio su tela<\/td>\n<\/tr>\n<tr>\n<td height=\"21\">Situato:<\/td>\n<td style=\"width: 452px\">Collezione privata, H. O. Havemeyer<\/td>\n<\/tr>\n<\/tbody>\n<colgroup>\n<col \/>\n<col \/> <\/colgroup>\n<\/table>\n<p>\u00a0<\/p>\n<div>\n<p>Monet trascorse gli ultimi anni della sua vita a Giverny. Accanto alla sua residenza fece costruire un giardino con un laghetto e un ponte ad arco in stile giapponese. Nel 1900 espone una serie di dieci tele con il motivo di questo giardino con laghetto, presentando lo stesso soggetto in diverse condizioni di luce.<\/p>\n<\/div>\n<div>\n<p>\u00a0<\/p>\n<\/div>\n<div>\n<p>Il semplice disegno di questo olio su tela, con un ponte giapponese in primo piano, \u00e8 ripetuto in molti altri dipinti di Monet. Le fresche sfumature verdi della crescita nel giardino evocano la sensazione di una giornata di inizio estate.<\/p>\n<\/div>\n<div>\n<p>\u00a0<\/p>\n<\/div>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column]\t<div class=\"et-image-580 et-image  full   et_image_link\">\n\t\t<div class=\"et-image-inner \">\n\t\t\t\t\t\t\t<div class=\"et-image-thumb \">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Claude-Monet-The-Water-Lily-Pond-Aka-Japanese-Bridge-scaled.jpg\" class=\"attachment-full\" alt=\"Claude Monet The Water Lily Pond (Aka Japanese Bridge) quadro su tela - riproduzione a mano di una riproduzione di quadri\" title=\"Claude Monet The Water Lily Pond (Aka Japanese Bridge) quadro su tela - riproduzione a mano di una riproduzione di quadri\" srcset=\"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Claude-Monet-The-Water-Lily-Pond-Aka-Japanese-Bridge-scaled.jpg 2560w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Claude-Monet-The-Water-Lily-Pond-Aka-Japanese-Bridge-600x450.jpg 600w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Claude-Monet-The-Water-Lily-Pond-Aka-Japanese-Bridge-scaled-1200x900.jpg 1200w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Claude-Monet-The-Water-Lily-Pond-Aka-Japanese-Bridge-300x225.jpg 300w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Claude-Monet-The-Water-Lily-Pond-Aka-Japanese-Bridge-1024x768.jpg 1024w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Claude-Monet-The-Water-Lily-Pond-Aka-Japanese-Bridge-768x576.jpg 768w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Claude-Monet-The-Water-Lily-Pond-Aka-Japanese-Bridge-1536x1152.jpg 1536w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Claude-Monet-The-Water-Lily-Pond-Aka-Japanese-Bridge-2048x1536.jpg 2048w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Claude-Monet-The-Water-Lily-Pond-Aka-Japanese-Bridge-150x113.jpg 150w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Claude-Monet-The-Water-Lily-Pond-Aka-Japanese-Bridge-1320x990.jpg 1320w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Claude-Monet-The-Water-Lily-Pond-Aka-Japanese-Bridge-900x675.jpg 900w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n  [\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Claude Monet \u2013 Lo stagno delle ninfee (noto anche come ponte giapponese) \u00a0 Anno di creazione: 1899 Dimensione originale: 73,3 cm x 92,7 cm Stile colore: Impressionismo Tecnica originale: Olio su tela Situato: Collezione privata, H. O. Havemeyer \u00a0 Monet trascorse gli ultimi anni della sua vita a Giverny. [&hellip;]<\/p>\n","protected":false},"featured_media":35767,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[4176],"product_tag":[4232,4245,4246,4253],"class_list":["post-38056","product","type-product","status-publish","has-post-thumbnail","product_cat-claude-monet","product_tag-monet-it","product_tag-riproduzione","product_tag-riproduzione-it","product_tag-un-pittore","pa_dimenzija-120-x-150-cm","pa_dimenzija-150-x-190-cm","pa_dimenzija-40-x-50-cm","pa_dimenzija-50-x-60-cm","pa_dimenzija-60-x-70-cm","pa_dimenzija-73-x-92-cm","pa_dimenzija-80-x-100-cm","pa_dimenzija-90-x-110-cm","pa_oblika-verticale","pa_okvir-sensa-cornice","pa_podokvir-no","pa_podokvir-si","first","onbackorder","purchasable","product-type-variable","has-default-attributes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Claude Monet \u2013 Lo stagno delle ninfee (Ponte giapponese)<\/title>\n<meta name=\"description\" content=\"Claude Monet \u2013 Lo stagno delle ninfee (Ponte giapponese) - Riproduzioni di quadri d&#039;arte dipinte a mano al 100% su tela. Cornici per quadri, vendita e produzione di dimensioni su ordinazione.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/svetslik.si\/it\/claude-monet\/the-water-lily-pond-aka-japanese-bridge\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Claude Monet \u2013 Lo stagno delle ninfee (Ponte giapponese)\" \/>\n<meta property=\"og:description\" content=\"100% riproduzioni dipinte a mano di quadri di pittori famosi e dipinti su tela.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svetslik.si\/it\/claude-monet\/the-water-lily-pond-aka-japanese-bridge\/\" \/>\n<meta property=\"og:site_name\" content=\"SVETSLIK.SI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/svetslik.si\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-22T20:01:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/08\/image_The-Water-Lily-Pond-Aka-Japanese-Bridge-Claude-Monet_680-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2049\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@svetslik\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e0\" \/>\n\t<meta name=\"twitter:data1\" content=\"Su ordinazione\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/claude-monet\\\/the-water-lily-pond-aka-japanese-bridge\\\/\",\"url\":\"https:\\\/\\\/svetslik.si\\\/it\\\/claude-monet\\\/the-water-lily-pond-aka-japanese-bridge\\\/\",\"name\":\"Claude Monet \u2013 Lo stagno delle ninfee (Ponte giapponese)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/claude-monet\\\/the-water-lily-pond-aka-japanese-bridge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/claude-monet\\\/the-water-lily-pond-aka-japanese-bridge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/image_The-Water-Lily-Pond-Aka-Japanese-Bridge-Claude-Monet_680-scaled.jpg\",\"datePublished\":\"2021-09-02T15:42:32+00:00\",\"dateModified\":\"2026-03-22T20:01:16+00:00\",\"description\":\"Claude Monet \u2013 Lo stagno delle ninfee (Ponte giapponese) - Riproduzioni di quadri d'arte dipinte a mano al 100% su tela. Cornici per quadri, vendita e produzione di dimensioni su ordinazione.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/claude-monet\\\/the-water-lily-pond-aka-japanese-bridge\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/svetslik.si\\\/it\\\/claude-monet\\\/the-water-lily-pond-aka-japanese-bridge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/claude-monet\\\/the-water-lily-pond-aka-japanese-bridge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/image_The-Water-Lily-Pond-Aka-Japanese-Bridge-Claude-Monet_680-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/image_The-Water-Lily-Pond-Aka-Japanese-Bridge-Claude-Monet_680-scaled.jpg\",\"width\":2049,\"height\":2560,\"caption\":\"Claude Monet Il laghetto delle ninfee, conosciuto anche come Il ponte giapponese Riproduzioni dipinte a mano di famosi pittori, quadri moderni, quadri artistici per la parete\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/claude-monet\\\/the-water-lily-pond-aka-japanese-bridge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Quadri su tela\",\"item\":\"https:\\\/\\\/svetslik.si\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vendita di dipinti\",\"item\":\"https:\\\/\\\/svetslik.si\\\/prodaja-slik\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Claude Monet &#8211; The Water Lily Pond (Aka Japanese Bridge)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/svetslik.si\\\/it\\\/\",\"name\":\"SVETSLIK.SI\",\"description\":\"100% riproduzioni dipinte a mano di quadri di pittori famosi e dipinti su tela.\",\"publisher\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/svetslik.si\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Store\"],\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#organization\",\"name\":\"SvetSlik.si\",\"url\":\"https:\\\/\\\/svetslik.si\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-512.png\",\"contentUrl\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-512.png\",\"width\":512,\"height\":512,\"caption\":\"SvetSlik.si\"},\"image\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/svetslik.si\",\"https:\\\/\\\/x.com\\\/svetslik\",\"https:\\\/\\\/www.instagram.com\\\/svetslik.si\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/svetslik-si\"],\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Zgornje Bitnje 146a\",\"addressLocality\":\"\u017dabnica\",\"postalCode\":\"4209\",\"addressCountry\":\"SI\"},\"hasMap\":\"https:\\\/\\\/www.google.com\\\/maps\\\/place\\\/?q=place_id:ChIJaybyg-XHekcRwZCqYrxOGjY\",\"telephone\":\"+38651675637\",\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"https:\\\/\\\/schema.org\\\/Monday\",\"https:\\\/\\\/schema.org\\\/Tuesday\",\"https:\\\/\\\/schema.org\\\/Wednesday\",\"https:\\\/\\\/schema.org\\\/Thursday\",\"https:\\\/\\\/schema.org\\\/Friday\"],\"opens\":\"09:00\",\"closes\":\"20:00\"}],\"description\":\"Dipinti a mano su tela \u2013 ordina online o via e-mail. Visita possibile previo appuntamento.\",\"knowsAbout\":[\"dipinti su tela\",\"dipinti a mano su tela\",\"riproduzioni di dipinti\",\"olio su tela\",\"acrilico su tela\",\"arte moderna astratta\",\"pittura su commissione\",\"quadri su ordinazione\",\"incorniciatura di quadri\",\"quadri di artisti famosi\",\"quadri moderni per la casa\",\"dipinto come regalo\",\"tele personalizzate\",\"spedizione quadri\",\"galleria d'arte\"]}]}<\/script>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"48__\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Claude Monet \u2013 Lo stagno delle ninfee (Ponte giapponese)","description":"Claude Monet \u2013 Lo stagno delle ninfee (Ponte giapponese) - Riproduzioni di quadri d'arte dipinte a mano al 100% su tela. Cornici per quadri, vendita e produzione di dimensioni su ordinazione.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/svetslik.si\/it\/claude-monet\/the-water-lily-pond-aka-japanese-bridge\/","og_locale":"it_IT","og_type":"article","og_title":"Claude Monet \u2013 Lo stagno delle ninfee (Ponte giapponese)","og_description":"100% riproduzioni dipinte a mano di quadri di pittori famosi e dipinti su tela.","og_url":"https:\/\/svetslik.si\/it\/claude-monet\/the-water-lily-pond-aka-japanese-bridge\/","og_site_name":"SVETSLIK.SI","article_publisher":"https:\/\/www.facebook.com\/svetslik.si","article_modified_time":"2026-03-22T20:01:16+00:00","og_image":[{"width":2049,"height":2560,"url":"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/08\/image_The-Water-Lily-Pond-Aka-Japanese-Bridge-Claude-Monet_680-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@svetslik","twitter_misc":{"Disponibilit\u00e0":"Su ordinazione"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/svetslik.si\/it\/claude-monet\/the-water-lily-pond-aka-japanese-bridge\/","url":"https:\/\/svetslik.si\/it\/claude-monet\/the-water-lily-pond-aka-japanese-bridge\/","name":"Claude Monet \u2013 Lo stagno delle ninfee (Ponte giapponese)","isPartOf":{"@id":"https:\/\/svetslik.si\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/svetslik.si\/it\/claude-monet\/the-water-lily-pond-aka-japanese-bridge\/#primaryimage"},"image":{"@id":"https:\/\/svetslik.si\/it\/claude-monet\/the-water-lily-pond-aka-japanese-bridge\/#primaryimage"},"thumbnailUrl":"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/08\/image_The-Water-Lily-Pond-Aka-Japanese-Bridge-Claude-Monet_680-scaled.jpg","datePublished":"2021-09-02T15:42:32+00:00","dateModified":"2026-03-22T20:01:16+00:00","description":"Claude Monet \u2013 Lo stagno delle ninfee (Ponte giapponese) - Riproduzioni di quadri d'arte dipinte a mano al 100% su tela. Cornici per quadri, vendita e produzione di dimensioni su ordinazione.","breadcrumb":{"@id":"https:\/\/svetslik.si\/it\/claude-monet\/the-water-lily-pond-aka-japanese-bridge\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/svetslik.si\/it\/claude-monet\/the-water-lily-pond-aka-japanese-bridge\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/svetslik.si\/it\/claude-monet\/the-water-lily-pond-aka-japanese-bridge\/#primaryimage","url":"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/08\/image_The-Water-Lily-Pond-Aka-Japanese-Bridge-Claude-Monet_680-scaled.jpg","contentUrl":"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/08\/image_The-Water-Lily-Pond-Aka-Japanese-Bridge-Claude-Monet_680-scaled.jpg","width":2049,"height":2560,"caption":"Claude Monet Il laghetto delle ninfee, conosciuto anche come Il ponte giapponese Riproduzioni dipinte a mano di famosi pittori, quadri moderni, quadri artistici per la parete"},{"@type":"BreadcrumbList","@id":"https:\/\/svetslik.si\/it\/claude-monet\/the-water-lily-pond-aka-japanese-bridge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Quadri su tela","item":"https:\/\/svetslik.si\/it\/"},{"@type":"ListItem","position":2,"name":"Vendita di dipinti","item":"https:\/\/svetslik.si\/prodaja-slik\/"},{"@type":"ListItem","position":3,"name":"Claude Monet &#8211; The Water Lily Pond (Aka Japanese Bridge)"}]},{"@type":"WebSite","@id":"https:\/\/svetslik.si\/it\/#website","url":"https:\/\/svetslik.si\/it\/","name":"SVETSLIK.SI","description":"100% riproduzioni dipinte a mano di quadri di pittori famosi e dipinti su tela.","publisher":{"@id":"https:\/\/svetslik.si\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svetslik.si\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Store"],"@id":"https:\/\/svetslik.si\/it\/#organization","name":"SvetSlik.si","url":"https:\/\/svetslik.si\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/svetslik.si\/it\/#\/schema\/logo\/image\/","url":"https:\/\/svetslik.si\/wp-content\/uploads\/2020\/12\/logo-512.png","contentUrl":"https:\/\/svetslik.si\/wp-content\/uploads\/2020\/12\/logo-512.png","width":512,"height":512,"caption":"SvetSlik.si"},"image":{"@id":"https:\/\/svetslik.si\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/svetslik.si","https:\/\/x.com\/svetslik","https:\/\/www.instagram.com\/svetslik.si\/","https:\/\/www.linkedin.com\/company\/svetslik-si"],"address":{"@type":"PostalAddress","streetAddress":"Zgornje Bitnje 146a","addressLocality":"\u017dabnica","postalCode":"4209","addressCountry":"SI"},"hasMap":"https:\/\/www.google.com\/maps\/place\/?q=place_id:ChIJaybyg-XHekcRwZCqYrxOGjY","telephone":"+38651675637","openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["https:\/\/schema.org\/Monday","https:\/\/schema.org\/Tuesday","https:\/\/schema.org\/Wednesday","https:\/\/schema.org\/Thursday","https:\/\/schema.org\/Friday"],"opens":"09:00","closes":"20:00"}],"description":"Dipinti a mano su tela \u2013 ordina online o via e-mail. Visita possibile previo appuntamento.","knowsAbout":["dipinti su tela","dipinti a mano su tela","riproduzioni di dipinti","olio su tela","acrilico su tela","arte moderna astratta","pittura su commissione","quadri su ordinazione","incorniciatura di quadri","quadri di artisti famosi","quadri moderni per la casa","dipinto come regalo","tele personalizzate","spedizione quadri","galleria d'arte"]}]},"og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"48__","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product\/38056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/media\/35767"}],"wp:attachment":[{"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/media?parent=38056"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product_brand?post=38056"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product_cat?post=38056"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product_tag?post=38056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}