{"id":40872,"date":"2021-09-02T18:24:58","date_gmt":"2021-09-02T16:24:58","guid":{"rendered":"https:\/\/svetslik.si\/senza-categoria\/krik\/"},"modified":"2026-03-22T22:01:15","modified_gmt":"2026-03-22T21:01:15","slug":"krik","status":"publish","type":"product","link":"https:\/\/svetslik.si\/it\/edvard-munch\/krik\/","title":{"rendered":"Edvard Munch \u2013 L&#8217;urlo"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row css=\u201d.vc_custom_1722459049604{margin-bottom: 10px !important;}\u201d][vc_column]\t<div class=\"et-image-657 et-image     et_image_link\">\n\t\t<div class=\"et-image-inner \">\n\t\t\t\t\t\t\t<div class=\"et-image-thumb \">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1251\" src=\"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream.jpg\" class=\"attachment-full\" alt=\"Edvard Munch - The Scream - L&#039;urlo\" title=\"Edvard Munch - The Scream - L&#039;urlo\" srcset=\"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream.jpg 1000w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream-600x751.jpg 600w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream-240x300.jpg 240w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream-819x1024.jpg 819w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream-768x961.jpg 768w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream-120x150.jpg 120w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream-900x1126.jpg 900w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n  [\/vc_column][\/vc_row][vc_row css=\u201d.vc_custom_1722459049604{margin-bottom: 10px !important;}\u201d][vc_column]\t<div class=\"et-image-466 et-image     et_image_link\">\n\t\t<div class=\"et-image-inner \">\n\t\t\t\t\t\t\t<div class=\"et-image-thumb \">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1232\" src=\"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream2.jpg\" class=\"attachment-full\" alt=\"Edvard Munch - The Scream - L&#039;urlo\" title=\"Edvard Munch - The Scream - L&#039;urlo\" srcset=\"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream2.jpg 1000w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream2-600x739.jpg 600w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream2-244x300.jpg 244w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream2-831x1024.jpg 831w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream2-768x946.jpg 768w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream2-122x150.jpg 122w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream2-900x1109.jpg 900w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n  [\/vc_column][\/vc_row][vc_row css=\u201d.vc_custom_1722459049604{margin-bottom: 10px !important;}\u201d][vc_column]\t<div class=\"et-image-474 et-image     et_image_link\">\n\t\t<div class=\"et-image-inner \">\n\t\t\t\t\t\t\t<div class=\"et-image-thumb \">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1440\" src=\"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream3.jpg\" class=\"attachment-full\" alt=\"Edvard Munch - The Scream - L&#039;urlo\" title=\"Edvard Munch - The Scream - L&#039;urlo\" srcset=\"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream3.jpg 1000w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream3-600x864.jpg 600w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream3-208x300.jpg 208w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream3-711x1024.jpg 711w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream3-768x1106.jpg 768w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream3-104x150.jpg 104w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream3-900x1296.jpg 900w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n  [\/vc_column][\/vc_row][vc_row css=\u201d.vc_custom_1722459049604{margin-bottom: 10px !important;}\u201d][vc_column]\t<div class=\"et-image-924 et-image     et_image_link\">\n\t\t<div class=\"et-image-inner \">\n\t\t\t\t\t\t\t<div class=\"et-image-thumb \">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"690\" src=\"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream-4.jpg\" class=\"attachment-full\" alt=\"Edvard Munch - The Scream - L&#039;urlo\" title=\"Edvard Munch - The Scream - L&#039;urlo\" srcset=\"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream-4.jpg 1000w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream-4-600x414.jpg 600w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream-4-300x207.jpg 300w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream-4-768x530.jpg 768w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream-4-150x104.jpg 150w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream-4-900x621.jpg 900w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n  [\/vc_column][\/vc_row][vc_row css=\u201d.vc_custom_1722459049604{margin-bottom: 10px !important;}\u201d][vc_column]\t<div class=\"et-image-412 et-image     et_image_link\">\n\t\t<div class=\"et-image-inner \">\n\t\t\t\t\t\t\t<div class=\"et-image-thumb \">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"563\" src=\"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream-5.jpg\" class=\"attachment-full\" alt=\"Edvard Munch - The Scream - L&#039;urlo\" title=\"Edvard Munch - The Scream - L&#039;urlo\" srcset=\"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream-5.jpg 1000w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream-5-600x338.jpg 600w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream-5-300x169.jpg 300w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream-5-768x432.jpg 768w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream-5-150x84.jpg 150w, https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-\u2013-Krik-\u2013-The-Scream-5-900x507.jpg 900w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n  [\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]\n<h1>Edvard Munch \u2013 L\u2019urlo<\/h1>\n<p>\u00a0<\/p>\n<table border=\"0\" width=\"673\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td height=\"21\">Anno di creazione:<\/td>\n<td style=\"width: 493px;\">1893<\/td>\n<\/tr>\n<tr>\n<td height=\"21\">Dimensione originale:<\/td>\n<td style=\"width: 493px;\">73,5 cm x 91 cm<\/td>\n<\/tr>\n<tr>\n<td height=\"21\">Stile colore:<\/td>\n<td style=\"width: 493px;\">Espressionismo<\/td>\n<\/tr>\n<tr>\n<td height=\"21\">Tecnica originale:<\/td>\n<td>Olio, tempera, pastello su cartoncino<\/td>\n<\/tr>\n<tr>\n<td height=\"21\">Situato:<\/td>\n<td>Galleria Nazionale, Oslo<\/td>\n<\/tr>\n<\/tbody>\n<colgroup>\n<col \/>\n<col \/> <\/colgroup>\n<\/table>\n<p>Edvard Munch: maestro dell\u2019espressionismo e L\u2019urlo<\/p>\n<p>Edvard Munch (1863-1944) \u00e8 stato un pittore norvegese considerato uno dei pionieri dell\u2019espressionismo, un movimento artistico moderno caratterizzato dall\u2019attenzione alle emozioni soggettive e al mondo interiore dell\u2019artista. Il suo dipinto pi\u00f9 famoso L\u2019urlo \u00e8 una delle icone dell\u2019arte contemporanea ed \u00e8 diventato sinonimo dell\u2019artista stesso.<\/p>\n<p>\u201cThe Scream\u201d, noto anche come The Scream of Nature, \u00e8 stato dipinto nel 1893 e raffigura una figura con un volto angosciato che tiene la testa ed emette un urlo assetato di sangue. Sullo sfondo dell\u2019immagine c\u2019\u00e8 un cielo tempestoso e un fiordo, che aggiunge un senso di caos e angoscia. Si dice che il dipinto rappresenti i sentimenti di ansia, alienazione e disperazione esistenziale di Munch.<\/p>\n<p>Munch ha creato quattro versioni di The Scream, due a olio, una a pastello e una stampata. La prima versione fu dipinta a olio nel 1893 ed \u00e8 ora parte della collezione del Museo Nazionale di Oslo, in Norvegia. La seconda versione, dipinta nel 1895, \u00e8 considerata la pi\u00f9 iconica delle quattro e fa parte della collezione del Museo Munch di Oslo.<\/p>\n<p>L\u2019urlo \u00e8 diventato una delle opere d\u2019arte pi\u00f9 riconoscibili al mondo ed \u00e8 apparso in numerosi film, libri e programmi televisivi. \u00c8 stato anche oggetto di numerosi studi critici, in cui molti esperti hanno analizzato il soggetto del dipinto, che riguarda il disagio psicologico, la ricerca di un senso nella vita e l\u2019esperienza umana.<\/p>\n<p>L\u2019urlo di Munch ha avuto un\u2019influenza significativa sugli artisti successivi, in particolare quelli che hanno lavorato nelle aree dell\u2019espressionismo, del surrealismo e del neoespressionismo. Il dipinto continua a ispirare e deliziare il pubblico oggi, come potente promemoria della straordinaria capacit\u00e0 dell\u2019artista di esprimere emozioni complesse attraverso le sue opere.<\/p>\n<p>Possiamo concludere che L\u2019urlo di Edvard Munch \u00e8 un\u2019opera fondamentale dell\u2019arte contemporanea che ancora affascina e ispira il pubblico. Il suo tema senza tempo di angoscia esistenziale, ansia e ricerca di significato nella vita lo rende una delle opere d\u2019arte pi\u00f9 riconoscibili e rispettate al mondo. Che tu sia un amante dell\u2019arte, uno storico o semplicemente interessato a esplorare l\u2019esperienza umana, The Scream \u00e8 un dipinto da non perdere.<\/p>\n<p>Parole chiave: Edvard Munch, L\u2019urlo, espressionismo, arte moderna, volto angosciato, grido della natura, disperazione esistenziale, icona, Museo Munch, disagio psicologico, esperienza umana.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=\u201d.vc_custom_1722459049604{margin-bottom: 10px !important;}\u201d][vc_column][\/vc_column][\/vc_row][vc_row css=\u201d.vc_custom_1722459049604{margin-bottom: 10px !important;}\u201d][vc_column][\/vc_column][\/vc_row][vc_row css=\u201d.vc_custom_1722459049604{margin-bottom: 10px !important;}\u201d][vc_column][\/vc_column][\/vc_row][vc_row css=\u201d.vc_custom_1722459049604{margin-bottom: 10px !important;}\u201d][vc_column][\/vc_column][\/vc_row][vc_row css=\u201d.vc_custom_1722459049604{margin-bottom: 10px !important;}\u201d][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text] Edvard Munch \u2013 L\u2019urlo \u00a0 Anno di creazione: 1893 Dimensione originale: 73,5 cm x 91 cm Stile colore: Espressionismo Tecnica originale: Olio, tempera, pastello su cartoncino Situato: Galleria Nazionale, Oslo Edvard Munch: maestro dell\u2019espressionismo [&hellip;]<\/p>\n","protected":false},"featured_media":36386,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[4179],"product_tag":[4233,4246,4245,4253],"class_list":["post-40872","product","type-product","status-publish","has-post-thumbnail","product_cat-edvard-munch","product_tag-munch-it","product_tag-riproduzione-it","product_tag-riproduzione","product_tag-un-pittore","pa_dimenzija-110-x-140-cm","pa_dimenzija-130-x-160-cm","pa_dimenzija-150-x-190-cm","pa_dimenzija-40-x-50-cm","pa_dimenzija-50-x-60-cm","pa_dimenzija-60-x-70-cm","pa_dimenzija-74-x-91-cm","pa_dimenzija-90-x-110-cm","pa_oblika-verticale","pa_okvir-sensa-cornice","pa_podokvir-no","pa_podokvir-si","first","onbackorder","purchasable","product-type-variable","has-default-attributes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Edvard Munch \u2013 L&#039;urlo<\/title>\n<meta name=\"description\" content=\"Edvard Munch \u2013 L&#039;urlo - Riproduzioni di quadri d&#039;arte dipinte a mano al 100% su tela. Cornici per quadri, vendita e produzione di dimensioni su ordinazione.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/svetslik.si\/it\/edvard-munch\/krik\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Edvard Munch \u2013 L&#039;urlo\" \/>\n<meta property=\"og:description\" content=\"100% riproduzioni dipinte a mano di quadri di pittori famosi e dipinti su tela.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svetslik.si\/it\/edvard-munch\/krik\/\" \/>\n<meta property=\"og:site_name\" content=\"SVETSLIK.SI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/svetslik.si\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-22T21:01:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-Kirik-The-Scream.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1267\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@svetslik\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e0\" \/>\n\t<meta name=\"twitter:data1\" content=\"Su ordinazione\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/edvard-munch\\\/krik\\\/\",\"url\":\"https:\\\/\\\/svetslik.si\\\/it\\\/edvard-munch\\\/krik\\\/\",\"name\":\"Edvard Munch \u2013 L'urlo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/edvard-munch\\\/krik\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/edvard-munch\\\/krik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Edvard-Munch-Kirik-The-Scream.jpg\",\"datePublished\":\"2021-09-02T16:24:58+00:00\",\"dateModified\":\"2026-03-22T21:01:15+00:00\",\"description\":\"Edvard Munch \u2013 L'urlo - Riproduzioni di quadri d'arte dipinte a mano al 100% su tela. Cornici per quadri, vendita e produzione di dimensioni su ordinazione.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/edvard-munch\\\/krik\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/svetslik.si\\\/it\\\/edvard-munch\\\/krik\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/edvard-munch\\\/krik\\\/#primaryimage\",\"url\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Edvard-Munch-Kirik-The-Scream.jpg\",\"contentUrl\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Edvard-Munch-Kirik-The-Scream.jpg\",\"width\":1000,\"height\":1267,\"caption\":\"Edvard Munch - Il grido\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/edvard-munch\\\/krik\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Quadri su tela\",\"item\":\"https:\\\/\\\/svetslik.si\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vendita di dipinti\",\"item\":\"https:\\\/\\\/svetslik.si\\\/prodaja-slik\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Edvard Munch &#8211; The Scream &#8211; L&#8217;urlo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/svetslik.si\\\/it\\\/\",\"name\":\"SVETSLIK.SI\",\"description\":\"100% riproduzioni dipinte a mano di quadri di pittori famosi e dipinti su tela.\",\"publisher\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/svetslik.si\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Store\"],\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#organization\",\"name\":\"SvetSlik.si\",\"url\":\"https:\\\/\\\/svetslik.si\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-512.png\",\"contentUrl\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-512.png\",\"width\":512,\"height\":512,\"caption\":\"SvetSlik.si\"},\"image\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/svetslik.si\",\"https:\\\/\\\/x.com\\\/svetslik\",\"https:\\\/\\\/www.instagram.com\\\/svetslik.si\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/svetslik-si\"],\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Zgornje Bitnje 146a\",\"addressLocality\":\"\u017dabnica\",\"postalCode\":\"4209\",\"addressCountry\":\"SI\"},\"hasMap\":\"https:\\\/\\\/www.google.com\\\/maps\\\/place\\\/?q=place_id:ChIJaybyg-XHekcRwZCqYrxOGjY\",\"telephone\":\"+38651675637\",\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"https:\\\/\\\/schema.org\\\/Monday\",\"https:\\\/\\\/schema.org\\\/Tuesday\",\"https:\\\/\\\/schema.org\\\/Wednesday\",\"https:\\\/\\\/schema.org\\\/Thursday\",\"https:\\\/\\\/schema.org\\\/Friday\"],\"opens\":\"09:00\",\"closes\":\"20:00\"}],\"description\":\"Dipinti a mano su tela \u2013 ordina online o via e-mail. Visita possibile previo appuntamento.\",\"knowsAbout\":[\"dipinti su tela\",\"dipinti a mano su tela\",\"riproduzioni di dipinti\",\"olio su tela\",\"acrilico su tela\",\"arte moderna astratta\",\"pittura su commissione\",\"quadri su ordinazione\",\"incorniciatura di quadri\",\"quadri di artisti famosi\",\"quadri moderni per la casa\",\"dipinto come regalo\",\"tele personalizzate\",\"spedizione quadri\",\"galleria d'arte\"]}]}<\/script>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"566__\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Edvard Munch \u2013 L'urlo","description":"Edvard Munch \u2013 L'urlo - Riproduzioni di quadri d'arte dipinte a mano al 100% su tela. Cornici per quadri, vendita e produzione di dimensioni su ordinazione.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/svetslik.si\/it\/edvard-munch\/krik\/","og_locale":"it_IT","og_type":"article","og_title":"Edvard Munch \u2013 L'urlo","og_description":"100% riproduzioni dipinte a mano di quadri di pittori famosi e dipinti su tela.","og_url":"https:\/\/svetslik.si\/it\/edvard-munch\/krik\/","og_site_name":"SVETSLIK.SI","article_publisher":"https:\/\/www.facebook.com\/svetslik.si","article_modified_time":"2026-03-22T21:01:15+00:00","og_image":[{"width":1000,"height":1267,"url":"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-Kirik-The-Scream.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@svetslik","twitter_misc":{"Disponibilit\u00e0":"Su ordinazione"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/svetslik.si\/it\/edvard-munch\/krik\/","url":"https:\/\/svetslik.si\/it\/edvard-munch\/krik\/","name":"Edvard Munch \u2013 L'urlo","isPartOf":{"@id":"https:\/\/svetslik.si\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/svetslik.si\/it\/edvard-munch\/krik\/#primaryimage"},"image":{"@id":"https:\/\/svetslik.si\/it\/edvard-munch\/krik\/#primaryimage"},"thumbnailUrl":"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-Kirik-The-Scream.jpg","datePublished":"2021-09-02T16:24:58+00:00","dateModified":"2026-03-22T21:01:15+00:00","description":"Edvard Munch \u2013 L'urlo - Riproduzioni di quadri d'arte dipinte a mano al 100% su tela. Cornici per quadri, vendita e produzione di dimensioni su ordinazione.","breadcrumb":{"@id":"https:\/\/svetslik.si\/it\/edvard-munch\/krik\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/svetslik.si\/it\/edvard-munch\/krik\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/svetslik.si\/it\/edvard-munch\/krik\/#primaryimage","url":"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-Kirik-The-Scream.jpg","contentUrl":"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/09\/Edvard-Munch-Kirik-The-Scream.jpg","width":1000,"height":1267,"caption":"Edvard Munch - Il grido"},{"@type":"BreadcrumbList","@id":"https:\/\/svetslik.si\/it\/edvard-munch\/krik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Quadri su tela","item":"https:\/\/svetslik.si\/it\/"},{"@type":"ListItem","position":2,"name":"Vendita di dipinti","item":"https:\/\/svetslik.si\/prodaja-slik\/"},{"@type":"ListItem","position":3,"name":"Edvard Munch &#8211; The Scream &#8211; L&#8217;urlo"}]},{"@type":"WebSite","@id":"https:\/\/svetslik.si\/it\/#website","url":"https:\/\/svetslik.si\/it\/","name":"SVETSLIK.SI","description":"100% riproduzioni dipinte a mano di quadri di pittori famosi e dipinti su tela.","publisher":{"@id":"https:\/\/svetslik.si\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svetslik.si\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Store"],"@id":"https:\/\/svetslik.si\/it\/#organization","name":"SvetSlik.si","url":"https:\/\/svetslik.si\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/svetslik.si\/it\/#\/schema\/logo\/image\/","url":"https:\/\/svetslik.si\/wp-content\/uploads\/2020\/12\/logo-512.png","contentUrl":"https:\/\/svetslik.si\/wp-content\/uploads\/2020\/12\/logo-512.png","width":512,"height":512,"caption":"SvetSlik.si"},"image":{"@id":"https:\/\/svetslik.si\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/svetslik.si","https:\/\/x.com\/svetslik","https:\/\/www.instagram.com\/svetslik.si\/","https:\/\/www.linkedin.com\/company\/svetslik-si"],"address":{"@type":"PostalAddress","streetAddress":"Zgornje Bitnje 146a","addressLocality":"\u017dabnica","postalCode":"4209","addressCountry":"SI"},"hasMap":"https:\/\/www.google.com\/maps\/place\/?q=place_id:ChIJaybyg-XHekcRwZCqYrxOGjY","telephone":"+38651675637","openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["https:\/\/schema.org\/Monday","https:\/\/schema.org\/Tuesday","https:\/\/schema.org\/Wednesday","https:\/\/schema.org\/Thursday","https:\/\/schema.org\/Friday"],"opens":"09:00","closes":"20:00"}],"description":"Dipinti a mano su tela \u2013 ordina online o via e-mail. Visita possibile previo appuntamento.","knowsAbout":["dipinti su tela","dipinti a mano su tela","riproduzioni di dipinti","olio su tela","acrilico su tela","arte moderna astratta","pittura su commissione","quadri su ordinazione","incorniciatura di quadri","quadri di artisti famosi","quadri moderni per la casa","dipinto come regalo","tele personalizzate","spedizione quadri","galleria d'arte"]}]},"og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"566__","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product\/40872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/media\/36386"}],"wp:attachment":[{"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/media?parent=40872"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product_brand?post=40872"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product_cat?post=40872"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product_tag?post=40872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}