{"id":43580,"date":"2021-09-02T18:36:49","date_gmt":"2021-09-02T16:36:49","guid":{"rendered":"https:\/\/svetslik.si\/senza-categoria\/moderna-slika-v-prostoru-i\/"},"modified":"2026-07-09T14:30:56","modified_gmt":"2026-07-09T12:30:56","slug":"quadri-moderni-nello-spazio-i","status":"publish","type":"product","link":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-nello-spazio-i\/","title":{"rendered":"Quadri moderni &#8211; Nello spazio I"},"content":{"rendered":"<p>Un pannello verticale blu-nero scuro sulla met\u00e0 sinistra del quadro proietta un\u2019ombra drammatica, cui il lato destro \u2014 in toni bronzo-oro e oliva con texture plastica \u2014 si contrappone con decisione. Al centro della met\u00e0 destra vi sono due fiori dorati: uno in una cornice quadrata in rilievo, l\u2019altro su uno stelo sottile al di sotto, entrambi con superfici finemente lavorate. Un ornamento argenteo con una spirale sinuosa nell\u2019angolo in alto a destra aggiunge un elegante tratto calligrafico. L\u2019insieme \u00e8 scuro e sommesso, ma ricco di vita interiore \u2014 ogni elemento \u00e8 collocato con precisione. Una decorazione murale in toni scuri per un ambiente che arrederete non con colori vivaci, ma con materia e silenzio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un pannello verticale blu-nero scuro sulla met\u00e0 sinistra del quadro proietta un\u2019ombra drammatica, cui il lato destro \u2014 in toni bronzo-oro e oliva con texture plastica \u2014 si contrappone con decisione. Al centro della met\u00e0 destra vi sono due fiori dorati: uno in una cornice quadrata in rilievo, l\u2019altro su [&hellip;]<\/p>\n","protected":false},"featured_media":35595,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[4192],"product_tag":[4261,4259,4264,4208,4216,4230,4254,4262,4257,4256,4255,4242],"class_list":["post-43580","product","type-product","status-publish","has-post-thumbnail","product_cat-quadri-moderni-un-pezzo","product_tag-decorazione-murale","product_tag-galleria-online","product_tag-quadri-artistici","product_tag-quadri-astratti-it","product_tag-quadri-decorative","product_tag-quadri-moderni","product_tag-quadri-moderni-it","product_tag-quadri-murali","product_tag-quadri-per-il-soggiorno","product_tag-quadri-per-pareti","product_tag-quadri-per-soggiorno","product_tag-vendere-quadri","pa_dimenzija-40-x-60-cm","pa_dimenzija-60-x-90-cm","pa_dimenzija-90-x-120-cm","pa_oblika-verticale","pa_okvir-sensa-cornice","pa_podokvir-no","pa_podokvir-si","first","onbackorder","purchasable","product-type-variable","has-default-attributes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Quadri moderni - Nello spazio I - SVETSLIK.SI - Dipinto al 100% fatto a mano<\/title>\n<meta name=\"description\" content=\"Quadri moderni - Nello spazio I - Riproduzioni di quadri d&#039;arte al 100% dipinti a mano su tela. Cornici per quadri, vendita e realizzazione di dimensioni su ordinazione.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-nello-spazio-i\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quadri moderni - Nello spazio I\" \/>\n<meta property=\"og:description\" content=\"100% riproduzioni dipinte a mano di quadri di pittori famosi e dipinti su tela.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-nello-spazio-i\/\" \/>\n<meta property=\"og:site_name\" content=\"SVETSLIK.SI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/svetslik.si\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-09T12:30:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/08\/image_Slika-V-prostoru-I_680.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"392\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@svetslik\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e0\" \/>\n\t<meta name=\"twitter:data1\" content=\"Su ordinazione\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/quadri-moderni-un-pezzo\\\/quadri-moderni-nello-spazio-i\\\/\",\"url\":\"https:\\\/\\\/svetslik.si\\\/it\\\/quadri-moderni-un-pezzo\\\/quadri-moderni-nello-spazio-i\\\/\",\"name\":\"Quadri moderni - Nello spazio I - SVETSLIK.SI - Dipinto al 100% fatto a mano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/quadri-moderni-un-pezzo\\\/quadri-moderni-nello-spazio-i\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/quadri-moderni-un-pezzo\\\/quadri-moderni-nello-spazio-i\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/image_Slika-V-prostoru-I_680.jpg\",\"datePublished\":\"2021-09-02T16:36:49+00:00\",\"dateModified\":\"2026-07-09T12:30:56+00:00\",\"description\":\"Quadri moderni - Nello spazio I - Riproduzioni di quadri d'arte al 100% dipinti a mano su tela. Cornici per quadri, vendita e realizzazione di dimensioni su ordinazione.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/quadri-moderni-un-pezzo\\\/quadri-moderni-nello-spazio-i\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/svetslik.si\\\/it\\\/quadri-moderni-un-pezzo\\\/quadri-moderni-nello-spazio-i\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/quadri-moderni-un-pezzo\\\/quadri-moderni-nello-spazio-i\\\/#primaryimage\",\"url\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/image_Slika-V-prostoru-I_680.jpg\",\"contentUrl\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/image_Slika-V-prostoru-I_680.jpg\",\"width\":392,\"height\":680,\"caption\":\"quadri moderni\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/quadri-moderni-un-pezzo\\\/quadri-moderni-nello-spazio-i\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Quadri su tela\",\"item\":\"https:\\\/\\\/svetslik.si\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vendita di dipinti\",\"item\":\"https:\\\/\\\/svetslik.si\\\/prodaja-slik\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quadri moderni &#8211; Nello spazio I\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/svetslik.si\\\/it\\\/\",\"name\":\"SVETSLIK.SI\",\"description\":\"100% riproduzioni dipinte a mano di quadri di pittori famosi e dipinti su tela.\",\"publisher\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/svetslik.si\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Store\"],\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#organization\",\"name\":\"SvetSlik.si\",\"url\":\"https:\\\/\\\/svetslik.si\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-512.png\",\"contentUrl\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-512.png\",\"width\":512,\"height\":512,\"caption\":\"SvetSlik.si\"},\"image\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/svetslik.si\",\"https:\\\/\\\/x.com\\\/svetslik\",\"https:\\\/\\\/www.instagram.com\\\/svetslik.si\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/svetslik-si\"],\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Zgornje Bitnje 146a\",\"addressLocality\":\"\u017dabnica\",\"postalCode\":\"4209\",\"addressCountry\":\"SI\"},\"hasMap\":\"https:\\\/\\\/www.google.com\\\/maps\\\/place\\\/?q=place_id:ChIJaybyg-XHekcRwZCqYrxOGjY\",\"telephone\":\"+38651675637\",\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"https:\\\/\\\/schema.org\\\/Monday\",\"https:\\\/\\\/schema.org\\\/Tuesday\",\"https:\\\/\\\/schema.org\\\/Wednesday\",\"https:\\\/\\\/schema.org\\\/Thursday\",\"https:\\\/\\\/schema.org\\\/Friday\"],\"opens\":\"09:00\",\"closes\":\"20:00\"}],\"description\":\"Dipinti a mano su tela \u2013 ordina online o via e-mail. Visita possibile previo appuntamento.\",\"knowsAbout\":[\"dipinti su tela\",\"dipinti a mano su tela\",\"riproduzioni di dipinti\",\"olio su tela\",\"acrilico su tela\",\"arte moderna astratta\",\"pittura su commissione\",\"quadri su ordinazione\",\"incorniciatura di quadri\",\"quadri di artisti famosi\",\"quadri moderni per la casa\",\"dipinto come regalo\",\"tele personalizzate\",\"spedizione quadri\",\"galleria d'arte\"]}]}<\/script>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"652__\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Quadri moderni - Nello spazio I - SVETSLIK.SI - Dipinto al 100% fatto a mano","description":"Quadri moderni - Nello spazio I - Riproduzioni di quadri d'arte al 100% dipinti a mano su tela. Cornici per quadri, vendita e realizzazione di dimensioni su ordinazione.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-nello-spazio-i\/","og_locale":"it_IT","og_type":"article","og_title":"Quadri moderni - Nello spazio I","og_description":"100% riproduzioni dipinte a mano di quadri di pittori famosi e dipinti su tela.","og_url":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-nello-spazio-i\/","og_site_name":"SVETSLIK.SI","article_publisher":"https:\/\/www.facebook.com\/svetslik.si","article_modified_time":"2026-07-09T12:30:56+00:00","og_image":[{"width":392,"height":680,"url":"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/08\/image_Slika-V-prostoru-I_680.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@svetslik","twitter_misc":{"Disponibilit\u00e0":"Su ordinazione"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-nello-spazio-i\/","url":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-nello-spazio-i\/","name":"Quadri moderni - Nello spazio I - SVETSLIK.SI - Dipinto al 100% fatto a mano","isPartOf":{"@id":"https:\/\/svetslik.si\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-nello-spazio-i\/#primaryimage"},"image":{"@id":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-nello-spazio-i\/#primaryimage"},"thumbnailUrl":"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/08\/image_Slika-V-prostoru-I_680.jpg","datePublished":"2021-09-02T16:36:49+00:00","dateModified":"2026-07-09T12:30:56+00:00","description":"Quadri moderni - Nello spazio I - Riproduzioni di quadri d'arte al 100% dipinti a mano su tela. Cornici per quadri, vendita e realizzazione di dimensioni su ordinazione.","breadcrumb":{"@id":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-nello-spazio-i\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-nello-spazio-i\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-nello-spazio-i\/#primaryimage","url":"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/08\/image_Slika-V-prostoru-I_680.jpg","contentUrl":"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/08\/image_Slika-V-prostoru-I_680.jpg","width":392,"height":680,"caption":"quadri moderni"},{"@type":"BreadcrumbList","@id":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-nello-spazio-i\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Quadri su tela","item":"https:\/\/svetslik.si\/it\/"},{"@type":"ListItem","position":2,"name":"Vendita di dipinti","item":"https:\/\/svetslik.si\/prodaja-slik\/"},{"@type":"ListItem","position":3,"name":"Quadri moderni &#8211; Nello spazio I"}]},{"@type":"WebSite","@id":"https:\/\/svetslik.si\/it\/#website","url":"https:\/\/svetslik.si\/it\/","name":"SVETSLIK.SI","description":"100% riproduzioni dipinte a mano di quadri di pittori famosi e dipinti su tela.","publisher":{"@id":"https:\/\/svetslik.si\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svetslik.si\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Store"],"@id":"https:\/\/svetslik.si\/it\/#organization","name":"SvetSlik.si","url":"https:\/\/svetslik.si\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/svetslik.si\/it\/#\/schema\/logo\/image\/","url":"https:\/\/svetslik.si\/wp-content\/uploads\/2020\/12\/logo-512.png","contentUrl":"https:\/\/svetslik.si\/wp-content\/uploads\/2020\/12\/logo-512.png","width":512,"height":512,"caption":"SvetSlik.si"},"image":{"@id":"https:\/\/svetslik.si\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/svetslik.si","https:\/\/x.com\/svetslik","https:\/\/www.instagram.com\/svetslik.si\/","https:\/\/www.linkedin.com\/company\/svetslik-si"],"address":{"@type":"PostalAddress","streetAddress":"Zgornje Bitnje 146a","addressLocality":"\u017dabnica","postalCode":"4209","addressCountry":"SI"},"hasMap":"https:\/\/www.google.com\/maps\/place\/?q=place_id:ChIJaybyg-XHekcRwZCqYrxOGjY","telephone":"+38651675637","openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["https:\/\/schema.org\/Monday","https:\/\/schema.org\/Tuesday","https:\/\/schema.org\/Wednesday","https:\/\/schema.org\/Thursday","https:\/\/schema.org\/Friday"],"opens":"09:00","closes":"20:00"}],"description":"Dipinti a mano su tela \u2013 ordina online o via e-mail. Visita possibile previo appuntamento.","knowsAbout":["dipinti su tela","dipinti a mano su tela","riproduzioni di dipinti","olio su tela","acrilico su tela","arte moderna astratta","pittura su commissione","quadri su ordinazione","incorniciatura di quadri","quadri di artisti famosi","quadri moderni per la casa","dipinto come regalo","tele personalizzate","spedizione quadri","galleria d'arte"]}]},"og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"652__","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product\/43580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/media\/35595"}],"wp:attachment":[{"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/media?parent=43580"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product_brand?post=43580"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product_cat?post=43580"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product_tag?post=43580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}