{"id":44611,"date":"2021-09-02T19:11:14","date_gmt":"2021-09-02T17:11:14","guid":{"rendered":"https:\/\/svetslik.si\/senza-categoria\/dekorativna-slika-cvet-strasti\/"},"modified":"2026-07-11T21:55:40","modified_gmt":"2026-07-11T19:55:40","slug":"quadri-decorativi-fiore-della-passione","status":"publish","type":"product","link":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-decorativi-fiore-della-passione\/","title":{"rendered":"Quadri decorativi &#8211; Fiore della passione"},"content":{"rendered":"<p>Da un centro scuro, quasi nero, esplode una forma \u2014 rami rossi, fuoco o un fiore che si diffonde in uno sfondo dorato. Il quadro \u00e8 verticale e dinamico: una massa scura in basso che si apre verso l\u2019alto nella luce. Rosso e oro sono caldi e drammatici, e il contrasto con il nucleo nero lo rende serio. Un dipinto a mano con una forza espressiva difficile da ignorare. Arte astratta sulla passione \u2014 non un sentimento quieto ma una forza fisica \u2014 un quadro d\u2019arte da parete che mostra proprio questo. Un quadro d\u2019arte da parete dall\u2019intensit\u00e0 esplosiva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da un centro scuro, quasi nero, esplode una forma \u2014 rami rossi, fuoco o un fiore che si diffonde in uno sfondo dorato. Il quadro \u00e8 verticale e dinamico: una massa scura in basso che si apre verso l\u2019alto nella luce. Rosso e oro sono caldi e drammatici, e il [&hellip;]<\/p>\n","protected":false},"featured_media":34893,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[4192],"product_tag":[4261,4259,4264,4208,4216,4230,4254,4262,4257,4256,4255,4242],"class_list":["post-44611","product","type-product","status-publish","has-post-thumbnail","product_cat-quadri-moderni-un-pezzo","product_tag-decorazione-murale","product_tag-galleria-online","product_tag-quadri-artistici","product_tag-quadri-astratti-it","product_tag-quadri-decorative","product_tag-quadri-moderni","product_tag-quadri-moderni-it","product_tag-quadri-murali","product_tag-quadri-per-il-soggiorno","product_tag-quadri-per-pareti","product_tag-quadri-per-soggiorno","product_tag-vendere-quadri","pa_dimenzija-40-x-60-cm","pa_dimenzija-50-x-80-cm","pa_dimenzija-70-x-110-cm","pa_dimenzija-90-x-140-cm","pa_oblika-verticale","pa_okvir-sensa-cornice","pa_podokvir-no","pa_podokvir-si","first","onbackorder","purchasable","product-type-variable","has-default-attributes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Quadri decorativi - Fiore della passione - SVETSLIK.SI - Dipinto al 100% fatto a mano<\/title>\n<meta name=\"description\" content=\"Quadri decorativi - Fiore della passione - Riproduzioni di quadri d&#039;arte al 100% dipinti a mano su tela. Cornici per quadri, vendita e realizzazione di dimensioni su ordinazione.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-decorativi-fiore-della-passione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quadri decorativi - Fiore della passione\" \/>\n<meta property=\"og:description\" content=\"100% riproduzioni dipinte a mano di quadri di pittori famosi e dipinti su tela.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-decorativi-fiore-della-passione\/\" \/>\n<meta property=\"og:site_name\" content=\"SVETSLIK.SI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/svetslik.si\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T19:55:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/08\/image_Ambientalna-slika-Cvet-strasti_680.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"455\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@svetslik\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e0\" \/>\n\t<meta name=\"twitter:data1\" content=\"Su ordinazione\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/quadri-moderni-un-pezzo\\\/quadri-decorativi-fiore-della-passione\\\/\",\"url\":\"https:\\\/\\\/svetslik.si\\\/it\\\/quadri-moderni-un-pezzo\\\/quadri-decorativi-fiore-della-passione\\\/\",\"name\":\"Quadri decorativi - Fiore della passione - SVETSLIK.SI - Dipinto al 100% fatto a mano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/quadri-moderni-un-pezzo\\\/quadri-decorativi-fiore-della-passione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/quadri-moderni-un-pezzo\\\/quadri-decorativi-fiore-della-passione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/image_Ambientalna-slika-Cvet-strasti_680.jpg\",\"datePublished\":\"2021-09-02T17:11:14+00:00\",\"dateModified\":\"2026-07-11T19:55:40+00:00\",\"description\":\"Quadri decorativi - Fiore della passione - Riproduzioni di quadri d'arte al 100% dipinti a mano su tela. Cornici per quadri, vendita e realizzazione di dimensioni su ordinazione.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/quadri-moderni-un-pezzo\\\/quadri-decorativi-fiore-della-passione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/svetslik.si\\\/it\\\/quadri-moderni-un-pezzo\\\/quadri-decorativi-fiore-della-passione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/quadri-moderni-un-pezzo\\\/quadri-decorativi-fiore-della-passione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/image_Ambientalna-slika-Cvet-strasti_680.jpg\",\"contentUrl\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/image_Ambientalna-slika-Cvet-strasti_680.jpg\",\"width\":455,\"height\":680,\"caption\":\"Quadri moderni - Dipinto decorativo Fiore della passione\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/quadri-moderni-un-pezzo\\\/quadri-decorativi-fiore-della-passione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Quadri su tela\",\"item\":\"https:\\\/\\\/svetslik.si\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vendita di dipinti\",\"item\":\"https:\\\/\\\/svetslik.si\\\/prodaja-slik\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quadri decorativi &#8211; Fiore della passione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/svetslik.si\\\/it\\\/\",\"name\":\"SVETSLIK.SI\",\"description\":\"100% riproduzioni dipinte a mano di quadri di pittori famosi e dipinti su tela.\",\"publisher\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/svetslik.si\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Store\"],\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#organization\",\"name\":\"SvetSlik.si\",\"url\":\"https:\\\/\\\/svetslik.si\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-512.png\",\"contentUrl\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-512.png\",\"width\":512,\"height\":512,\"caption\":\"SvetSlik.si\"},\"image\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/svetslik.si\",\"https:\\\/\\\/x.com\\\/svetslik\",\"https:\\\/\\\/www.instagram.com\\\/svetslik.si\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/svetslik-si\"],\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Zgornje Bitnje 146a\",\"addressLocality\":\"\u017dabnica\",\"postalCode\":\"4209\",\"addressCountry\":\"SI\"},\"hasMap\":\"https:\\\/\\\/www.google.com\\\/maps\\\/place\\\/?q=place_id:ChIJaybyg-XHekcRwZCqYrxOGjY\",\"telephone\":\"+38651675637\",\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"https:\\\/\\\/schema.org\\\/Monday\",\"https:\\\/\\\/schema.org\\\/Tuesday\",\"https:\\\/\\\/schema.org\\\/Wednesday\",\"https:\\\/\\\/schema.org\\\/Thursday\",\"https:\\\/\\\/schema.org\\\/Friday\"],\"opens\":\"09:00\",\"closes\":\"20:00\"}],\"description\":\"Dipinti a mano su tela \u2013 ordina online o via e-mail. Visita possibile previo appuntamento.\",\"knowsAbout\":[\"dipinti su tela\",\"dipinti a mano su tela\",\"riproduzioni di dipinti\",\"olio su tela\",\"acrilico su tela\",\"arte moderna astratta\",\"pittura su commissione\",\"quadri su ordinazione\",\"incorniciatura di quadri\",\"quadri di artisti famosi\",\"quadri moderni per la casa\",\"dipinto come regalo\",\"tele personalizzate\",\"spedizione quadri\",\"galleria d'arte\"]}]}<\/script>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"1001__\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Quadri decorativi - Fiore della passione - SVETSLIK.SI - Dipinto al 100% fatto a mano","description":"Quadri decorativi - Fiore della passione - Riproduzioni di quadri d'arte al 100% dipinti a mano su tela. Cornici per quadri, vendita e realizzazione di dimensioni su ordinazione.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-decorativi-fiore-della-passione\/","og_locale":"it_IT","og_type":"article","og_title":"Quadri decorativi - Fiore della passione","og_description":"100% riproduzioni dipinte a mano di quadri di pittori famosi e dipinti su tela.","og_url":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-decorativi-fiore-della-passione\/","og_site_name":"SVETSLIK.SI","article_publisher":"https:\/\/www.facebook.com\/svetslik.si","article_modified_time":"2026-07-11T19:55:40+00:00","og_image":[{"width":455,"height":680,"url":"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/08\/image_Ambientalna-slika-Cvet-strasti_680.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@svetslik","twitter_misc":{"Disponibilit\u00e0":"Su ordinazione"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-decorativi-fiore-della-passione\/","url":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-decorativi-fiore-della-passione\/","name":"Quadri decorativi - Fiore della passione - SVETSLIK.SI - Dipinto al 100% fatto a mano","isPartOf":{"@id":"https:\/\/svetslik.si\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-decorativi-fiore-della-passione\/#primaryimage"},"image":{"@id":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-decorativi-fiore-della-passione\/#primaryimage"},"thumbnailUrl":"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/08\/image_Ambientalna-slika-Cvet-strasti_680.jpg","datePublished":"2021-09-02T17:11:14+00:00","dateModified":"2026-07-11T19:55:40+00:00","description":"Quadri decorativi - Fiore della passione - Riproduzioni di quadri d'arte al 100% dipinti a mano su tela. Cornici per quadri, vendita e realizzazione di dimensioni su ordinazione.","breadcrumb":{"@id":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-decorativi-fiore-della-passione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-decorativi-fiore-della-passione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-decorativi-fiore-della-passione\/#primaryimage","url":"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/08\/image_Ambientalna-slika-Cvet-strasti_680.jpg","contentUrl":"https:\/\/svetslik.si\/wp-content\/uploads\/2021\/08\/image_Ambientalna-slika-Cvet-strasti_680.jpg","width":455,"height":680,"caption":"Quadri moderni - Dipinto decorativo Fiore della passione"},{"@type":"BreadcrumbList","@id":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-decorativi-fiore-della-passione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Quadri su tela","item":"https:\/\/svetslik.si\/it\/"},{"@type":"ListItem","position":2,"name":"Vendita di dipinti","item":"https:\/\/svetslik.si\/prodaja-slik\/"},{"@type":"ListItem","position":3,"name":"Quadri decorativi &#8211; Fiore della passione"}]},{"@type":"WebSite","@id":"https:\/\/svetslik.si\/it\/#website","url":"https:\/\/svetslik.si\/it\/","name":"SVETSLIK.SI","description":"100% riproduzioni dipinte a mano di quadri di pittori famosi e dipinti su tela.","publisher":{"@id":"https:\/\/svetslik.si\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svetslik.si\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Store"],"@id":"https:\/\/svetslik.si\/it\/#organization","name":"SvetSlik.si","url":"https:\/\/svetslik.si\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/svetslik.si\/it\/#\/schema\/logo\/image\/","url":"https:\/\/svetslik.si\/wp-content\/uploads\/2020\/12\/logo-512.png","contentUrl":"https:\/\/svetslik.si\/wp-content\/uploads\/2020\/12\/logo-512.png","width":512,"height":512,"caption":"SvetSlik.si"},"image":{"@id":"https:\/\/svetslik.si\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/svetslik.si","https:\/\/x.com\/svetslik","https:\/\/www.instagram.com\/svetslik.si\/","https:\/\/www.linkedin.com\/company\/svetslik-si"],"address":{"@type":"PostalAddress","streetAddress":"Zgornje Bitnje 146a","addressLocality":"\u017dabnica","postalCode":"4209","addressCountry":"SI"},"hasMap":"https:\/\/www.google.com\/maps\/place\/?q=place_id:ChIJaybyg-XHekcRwZCqYrxOGjY","telephone":"+38651675637","openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["https:\/\/schema.org\/Monday","https:\/\/schema.org\/Tuesday","https:\/\/schema.org\/Wednesday","https:\/\/schema.org\/Thursday","https:\/\/schema.org\/Friday"],"opens":"09:00","closes":"20:00"}],"description":"Dipinti a mano su tela \u2013 ordina online o via e-mail. Visita possibile previo appuntamento.","knowsAbout":["dipinti su tela","dipinti a mano su tela","riproduzioni di dipinti","olio su tela","acrilico su tela","arte moderna astratta","pittura su commissione","quadri su ordinazione","incorniciatura di quadri","quadri di artisti famosi","quadri moderni per la casa","dipinto come regalo","tele personalizzate","spedizione quadri","galleria d'arte"]}]},"og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"1001__","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product\/44611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/media\/34893"}],"wp:attachment":[{"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/media?parent=44611"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product_brand?post=44611"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product_cat?post=44611"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product_tag?post=44611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}