{"id":46783,"date":"2023-03-04T18:07:35","date_gmt":"2023-03-04T17:07:35","guid":{"rendered":"https:\/\/svetslik.si\/senza-categoria\/abstraktne-slike-e35\/"},"modified":"2026-07-13T19:08:55","modified_gmt":"2026-07-13T17:08:55","slug":"quadri-moderni-astratti-e35","status":"publish","type":"product","link":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-astratti-e35\/","title":{"rendered":"Quadro d&#8217;arte \u2013 Albero argentato"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row css=\u201d.vc_custom_1661405884285{margin-bottom: 10px !important;}\u201d][vc_column]\t<div class=\"et-image-888 et-image     et_image_link\">\n\t\t<div class=\"et-image-inner \">\n\t\t\t\t\t\t\t<div class=\"et-image-thumb \">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"722\" height=\"540\" src=\"https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktne-slike-E35a.jpg\" class=\"attachment-full\" alt=\"Quadri moderni astratti \u2013 E35\" title=\"Quadri moderni astratti \u2013 E35\" srcset=\"https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktne-slike-E35a.jpg 722w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktne-slike-E35a-600x449.jpg 600w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktne-slike-E35a-300x224.jpg 300w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktne-slike-E35a-16x12.jpg 16w, https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktne-slike-E35a-150x112.jpg 150w\" sizes=\"auto, (max-width: 722px) 100vw, 722px\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n  [\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=\u201d20px\u201d][\/vc_column][\/vc_row]\n<p>Questo quadro astratto su tela raffigura una composizione eterea, dove scintille e macchioline bianco-argento si condensano nella met\u00e0 superiore della tela in una forma che ricorda una chioma d\u2019albero orlata di brina invernale. Fluiscono dolcemente verso il basso e sfumano nel bianco puro, creando un senso del silenzio che conosce solo un mattino presto dopo una notte di neve. Questo quadro meditativo \u00e8 creato da migliaia di dettagli fini che insieme formano un unico insieme sereno e ipnotico. Questo silenzio invernale \u00e8 autentico \u2014 \u00e8 un quadro artistico dipinto a mano, in cui ogni riflesso argenteo \u00e8 nato con il movimento della mano dell\u2019artista. La palette bianco-argento lo rende adatto a spazi interni moderni, minimalisti o nordici. Un quadro da parete perfetto per chi cerca pace, purezza e freschezza visiva senza colore.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=\u201d.vc_custom_1661405884285{margin-bottom: 10px !important;}\u201d][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=\u201d20px\u201d][\/vc_column][\/vc_row] Questo quadro astratto su tela raffigura una composizione eterea, dove scintille e macchioline bianco-argento si condensano nella met\u00e0 superiore della tela in una forma che ricorda una chioma d\u2019albero orlata di brina invernale. Fluiscono dolcemente verso il basso e sfumano nel bianco puro, creando un [&hellip;]<\/p>\n","protected":false},"featured_media":37126,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[4192],"product_tag":[4261,4259,4264,4208,4216,4230,4254,4262,4257,4256,4255,4242],"class_list":["post-46783","product","type-product","status-publish","has-post-thumbnail","product_cat-quadri-moderni-un-pezzo","product_tag-decorazione-murale","product_tag-galleria-online","product_tag-quadri-artistici","product_tag-quadri-astratti-it","product_tag-quadri-decorative","product_tag-quadri-moderni","product_tag-quadri-moderni-it","product_tag-quadri-murali","product_tag-quadri-per-il-soggiorno","product_tag-quadri-per-pareti","product_tag-quadri-per-soggiorno","product_tag-vendere-quadri","pa_dimenzija-100-cm-x-159-cm","pa_dimenzija-110-cm-x-175-cm","pa_dimenzija-120-cm-x-191-cm","pa_dimenzija-130-cm-x-207-cm","pa_dimenzija-140-cm-x-223-cm","pa_dimenzija-150-cm-x-239-cm","pa_dimenzija-160-cm-x-255-cm","pa_dimenzija-170-cm-x-271-cm","pa_dimenzija-180-cm-x-287-cm","pa_dimenzija-200-cm-x-319-cm","pa_dimenzija-40-cm-x-63-cm","pa_dimenzija-50-cm-x-79-cm","pa_dimenzija-60-cm-x-95-cm","pa_dimenzija-70-cm-x-111-cm","pa_dimenzija-80-cm-x-127-cm","pa_dimenzija-90-cm-x-143-cm","pa_oblika-verticale","pa_okvir-sensa-cornice","pa_podokvir-no","pa_podokvir-si","first","onbackorder","purchasable","product-type-variable","has-default-attributes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Quadro d&#039;arte \u2013 Albero argentato - SVETSLIK.SI - Dipinto al 100% fatto a mano<\/title>\n<meta name=\"description\" content=\"Quadro d&#039;arte \u2013 Albero argentato - Riproduzioni di quadri d&#039;arte al 100% dipinti a mano su tela. Cornici per quadri, vendita e realizzazione di dimensioni su ordinazione.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-astratti-e35\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quadro d&#039;arte \u2013 Albero argentato\" \/>\n<meta property=\"og:description\" content=\"100% riproduzioni dipinte a mano di quadri di pittori famosi e dipinti su tela.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-astratti-e35\/\" \/>\n<meta property=\"og:site_name\" content=\"SVETSLIK.SI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/svetslik.si\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-13T17:08:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktne-slike-E35.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"533\" \/>\n\t<meta property=\"og:image:height\" content=\"823\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@svetslik\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e0\" \/>\n\t<meta name=\"twitter:data1\" content=\"Su ordinazione\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/quadri-moderni-un-pezzo\\\/quadri-moderni-astratti-e35\\\/\",\"url\":\"https:\\\/\\\/svetslik.si\\\/it\\\/quadri-moderni-un-pezzo\\\/quadri-moderni-astratti-e35\\\/\",\"name\":\"Quadro d'arte \u2013 Albero argentato - SVETSLIK.SI - Dipinto al 100% fatto a mano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/quadri-moderni-un-pezzo\\\/quadri-moderni-astratti-e35\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/quadri-moderni-un-pezzo\\\/quadri-moderni-astratti-e35\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/abstraktne-slike-E35.jpg\",\"datePublished\":\"2023-03-04T17:07:35+00:00\",\"dateModified\":\"2026-07-13T17:08:55+00:00\",\"description\":\"Quadro d'arte \u2013 Albero argentato - Riproduzioni di quadri d'arte al 100% dipinti a mano su tela. Cornici per quadri, vendita e realizzazione di dimensioni su ordinazione.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/quadri-moderni-un-pezzo\\\/quadri-moderni-astratti-e35\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/svetslik.si\\\/it\\\/quadri-moderni-un-pezzo\\\/quadri-moderni-astratti-e35\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/quadri-moderni-un-pezzo\\\/quadri-moderni-astratti-e35\\\/#primaryimage\",\"url\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/abstraktne-slike-E35.jpg\",\"contentUrl\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/abstraktne-slike-E35.jpg\",\"width\":533,\"height\":823,\"caption\":\"Quadri moderni astratti \u2013 E35\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/quadri-moderni-un-pezzo\\\/quadri-moderni-astratti-e35\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Quadri su tela\",\"item\":\"https:\\\/\\\/svetslik.si\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vendita di dipinti\",\"item\":\"https:\\\/\\\/svetslik.si\\\/prodaja-slik\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quadri moderni astratti &#8211; E35\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/svetslik.si\\\/it\\\/\",\"name\":\"SVETSLIK.SI\",\"description\":\"100% riproduzioni dipinte a mano di quadri di pittori famosi e dipinti su tela.\",\"publisher\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/svetslik.si\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Store\"],\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#organization\",\"name\":\"SvetSlik.si\",\"url\":\"https:\\\/\\\/svetslik.si\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-512.png\",\"contentUrl\":\"https:\\\/\\\/svetslik.si\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-512.png\",\"width\":512,\"height\":512,\"caption\":\"SvetSlik.si\"},\"image\":{\"@id\":\"https:\\\/\\\/svetslik.si\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/svetslik.si\",\"https:\\\/\\\/x.com\\\/svetslik\",\"https:\\\/\\\/www.instagram.com\\\/svetslik.si\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/svetslik-si\"],\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Zgornje Bitnje 146a\",\"addressLocality\":\"\u017dabnica\",\"postalCode\":\"4209\",\"addressCountry\":\"SI\"},\"hasMap\":\"https:\\\/\\\/www.google.com\\\/maps\\\/place\\\/?q=place_id:ChIJaybyg-XHekcRwZCqYrxOGjY\",\"telephone\":\"+38651675637\",\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"https:\\\/\\\/schema.org\\\/Monday\",\"https:\\\/\\\/schema.org\\\/Tuesday\",\"https:\\\/\\\/schema.org\\\/Wednesday\",\"https:\\\/\\\/schema.org\\\/Thursday\",\"https:\\\/\\\/schema.org\\\/Friday\"],\"opens\":\"09:00\",\"closes\":\"20:00\"}],\"description\":\"Dipinti a mano su tela \u2013 ordina online o via e-mail. Visita possibile previo appuntamento.\",\"knowsAbout\":[\"dipinti su tela\",\"dipinti a mano su tela\",\"riproduzioni di dipinti\",\"olio su tela\",\"acrilico su tela\",\"arte moderna astratta\",\"pittura su commissione\",\"quadri su ordinazione\",\"incorniciatura di quadri\",\"quadri di artisti famosi\",\"quadri moderni per la casa\",\"dipinto come regalo\",\"tele personalizzate\",\"spedizione quadri\",\"galleria d'arte\"]}]}<\/script>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"1130_b\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Quadro d'arte \u2013 Albero argentato - SVETSLIK.SI - Dipinto al 100% fatto a mano","description":"Quadro d'arte \u2013 Albero argentato - Riproduzioni di quadri d'arte al 100% dipinti a mano su tela. Cornici per quadri, vendita e realizzazione di dimensioni su ordinazione.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-astratti-e35\/","og_locale":"it_IT","og_type":"article","og_title":"Quadro d'arte \u2013 Albero argentato","og_description":"100% riproduzioni dipinte a mano di quadri di pittori famosi e dipinti su tela.","og_url":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-astratti-e35\/","og_site_name":"SVETSLIK.SI","article_publisher":"https:\/\/www.facebook.com\/svetslik.si","article_modified_time":"2026-07-13T17:08:55+00:00","og_image":[{"width":533,"height":823,"url":"https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktne-slike-E35.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@svetslik","twitter_misc":{"Disponibilit\u00e0":"Su ordinazione"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-astratti-e35\/","url":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-astratti-e35\/","name":"Quadro d'arte \u2013 Albero argentato - SVETSLIK.SI - Dipinto al 100% fatto a mano","isPartOf":{"@id":"https:\/\/svetslik.si\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-astratti-e35\/#primaryimage"},"image":{"@id":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-astratti-e35\/#primaryimage"},"thumbnailUrl":"https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktne-slike-E35.jpg","datePublished":"2023-03-04T17:07:35+00:00","dateModified":"2026-07-13T17:08:55+00:00","description":"Quadro d'arte \u2013 Albero argentato - Riproduzioni di quadri d'arte al 100% dipinti a mano su tela. Cornici per quadri, vendita e realizzazione di dimensioni su ordinazione.","breadcrumb":{"@id":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-astratti-e35\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-astratti-e35\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-astratti-e35\/#primaryimage","url":"https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktne-slike-E35.jpg","contentUrl":"https:\/\/svetslik.si\/wp-content\/uploads\/2023\/03\/abstraktne-slike-E35.jpg","width":533,"height":823,"caption":"Quadri moderni astratti \u2013 E35"},{"@type":"BreadcrumbList","@id":"https:\/\/svetslik.si\/it\/quadri-moderni-un-pezzo\/quadri-moderni-astratti-e35\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Quadri su tela","item":"https:\/\/svetslik.si\/it\/"},{"@type":"ListItem","position":2,"name":"Vendita di dipinti","item":"https:\/\/svetslik.si\/prodaja-slik\/"},{"@type":"ListItem","position":3,"name":"Quadri moderni astratti &#8211; E35"}]},{"@type":"WebSite","@id":"https:\/\/svetslik.si\/it\/#website","url":"https:\/\/svetslik.si\/it\/","name":"SVETSLIK.SI","description":"100% riproduzioni dipinte a mano di quadri di pittori famosi e dipinti su tela.","publisher":{"@id":"https:\/\/svetslik.si\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svetslik.si\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Store"],"@id":"https:\/\/svetslik.si\/it\/#organization","name":"SvetSlik.si","url":"https:\/\/svetslik.si\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/svetslik.si\/it\/#\/schema\/logo\/image\/","url":"https:\/\/svetslik.si\/wp-content\/uploads\/2020\/12\/logo-512.png","contentUrl":"https:\/\/svetslik.si\/wp-content\/uploads\/2020\/12\/logo-512.png","width":512,"height":512,"caption":"SvetSlik.si"},"image":{"@id":"https:\/\/svetslik.si\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/svetslik.si","https:\/\/x.com\/svetslik","https:\/\/www.instagram.com\/svetslik.si\/","https:\/\/www.linkedin.com\/company\/svetslik-si"],"address":{"@type":"PostalAddress","streetAddress":"Zgornje Bitnje 146a","addressLocality":"\u017dabnica","postalCode":"4209","addressCountry":"SI"},"hasMap":"https:\/\/www.google.com\/maps\/place\/?q=place_id:ChIJaybyg-XHekcRwZCqYrxOGjY","telephone":"+38651675637","openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["https:\/\/schema.org\/Monday","https:\/\/schema.org\/Tuesday","https:\/\/schema.org\/Wednesday","https:\/\/schema.org\/Thursday","https:\/\/schema.org\/Friday"],"opens":"09:00","closes":"20:00"}],"description":"Dipinti a mano su tela \u2013 ordina online o via e-mail. Visita possibile previo appuntamento.","knowsAbout":["dipinti su tela","dipinti a mano su tela","riproduzioni di dipinti","olio su tela","acrilico su tela","arte moderna astratta","pittura su commissione","quadri su ordinazione","incorniciatura di quadri","quadri di artisti famosi","quadri moderni per la casa","dipinto come regalo","tele personalizzate","spedizione quadri","galleria d'arte"]}]},"og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"1130_b","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product\/46783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/media\/37126"}],"wp:attachment":[{"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/media?parent=46783"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product_brand?post=46783"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product_cat?post=46783"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/svetslik.si\/it\/wp-json\/wp\/v2\/product_tag?post=46783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}